{"id":1316,"date":"2020-01-10T19:08:25","date_gmt":"2020-01-10T19:08:25","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2020\/01\/10\/feira-da-penitenciaria-da-regiao-de-curitibanos-vende-produtos-agricolas-a-comunidade\/"},"modified":"2020-01-10T19:08:25","modified_gmt":"2020-01-10T19:08:25","slug":"feira-da-penitenciaria-da-regiao-de-curitibanos-vende-produtos-agricolas-a-comunidade","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/feira-da-penitenciaria-da-regiao-de-curitibanos-vende-produtos-agricolas-a-comunidade\/","title":{"rendered":"Feira da Penitenci\u00e1ria da Regi\u00e3o de Curitibanos vende produtos agr\u00edcolas \u00e0 comunidade"},"content":{"rendered":"<\/p>\n<p>Uma das vertentes do trabalho dos internos na Penitenci\u00e1ria da Regi\u00e3o de Curitibanos \u00e9 a produ\u00e7\u00e3o agr\u00edcola.De segunda a sexta-feira, das 9h \u00e0s 16h, uma feirinha na entrada da unidade garante produtos de \u00f3tima qualidade e fresquinhos aos moradores da regi\u00e3o, familiares de sentenciados e funcion\u00e1rios da unidade.<\/p>\n<p>De acordo com as pol\u00edticas laborais institu\u00eddas pela SAP e pelo Deap, a unidade prisional deve oferecer atividade qualificada e, preferencialmente, identificada com a voca\u00e7\u00e3o econ\u00f4mica da regi\u00e3o. Parab\u00e9ns equipe da Penitenci\u00e1ria da Regi\u00e3o de Curitibanos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Uma das vertentes do trabalho dos internos na Penitenci\u00e1ria da Regi\u00e3o de Curitibanos \u00e9 a produ\u00e7\u00e3o agr\u00edcola.De segunda a sexta-feira, das 9h \u00e0s 16h, uma feirinha na entrada da unidade garante produtos de \u00f3tima qualidade e fresquinhos aos moradores da regi\u00e3o, familiares de sentenciados e funcion\u00e1rios da unidade. De acordo com as pol\u00edticas laborais institu\u00eddas [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1315,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:19:14","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1316"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=1316"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1316\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=1316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=1316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=1316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}