{"id":13234,"date":"2012-08-16T18:15:26","date_gmt":"2012-08-16T21:15:26","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2012\/08\/16\/aula-inaugural-de-jiu-jitsu-e-defesa-pessoal-no-complexo-penitenciario-do-estado\/"},"modified":"2023-07-13T17:51:27","modified_gmt":"2023-07-13T20:51:27","slug":"aula-inaugural-de-jiu-jitsu-e-defesa-pessoal-no-complexo-penitenciario-do-estado","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/aula-inaugural-de-jiu-jitsu-e-defesa-pessoal-no-complexo-penitenciario-do-estado\/","title":{"rendered":"Aula inaugural de Jiu-jitsu e defesa pessoal no Complexo Penitenci\u00e1rio do Estado"},"content":{"rendered":"<p style=\"text-align: justify;\">Com a presen\u00e7a do Professor Piazza, essa \u00e9 mais uma forma valorizar e qualificar agentes penitenci\u00e1rios para sua \u00e1rdua miss\u00e3o. Os treinos ser\u00e3o abertos para todos os interessados e ocorrer\u00e3o de segunda a quinta-feira, em hor\u00e1rio definido, a fim de que todos os servidores do Complexo Penitenci\u00e1rio do Estado (S\u00e3o Pedro de Alc\u00e2ntara) e demais unidades tenham acesso durante o plant\u00e3o de vinte e quatro horas. A unidade ainda disponibilizou dez kimonos para as aulas. As aulas ser\u00e3o ministradas pelos Agentes Penitenci\u00e1rios e faixas pretas de Jiu-jitsu Jean Carpes e Carlos Alves.<\/p>","protected":false},"excerpt":{"rendered":"<p>Com a presen\u00e7a do Professor Piazza, essa \u00e9 mais uma forma valorizar e qualificar agentes penitenci\u00e1rios para sua \u00e1rdua miss\u00e3o. Os treinos ser\u00e3o abertos para todos os interessados e ocorrer\u00e3o de segunda a quinta-feira, em hor\u00e1rio definido, a fim de que todos os servidores do Complexo Penitenci\u00e1rio do Estado (S\u00e3o Pedro de Alc\u00e2ntara) e demais [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":13891,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:17:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13234"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=13234"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13234\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/13891"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=13234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=13234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=13234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}