{"id":13429,"date":"2014-09-08T19:40:49","date_gmt":"2014-09-08T22:40:49","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2014\/09\/08\/presos-de-campos-novos-concluem-series-iniciais\/"},"modified":"2023-07-13T17:53:00","modified_gmt":"2023-07-13T20:53:00","slug":"presos-de-campos-novos-concluem-series-iniciais","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/presos-de-campos-novos-concluem-series-iniciais\/","title":{"rendered":"Presos de Campos Novos concluem s\u00e9ries iniciais"},"content":{"rendered":"<p style=\"text-align: justify;\">N\u00e3o h\u00e1 barreiras para a educa\u00e7\u00e3o e nenhum impedimento pode interferir na busca pelo conhecimento. A prova de que a educa\u00e7\u00e3o supera todos os obst\u00e1culos \u00e9 difundida na Unidade Prisional Avan\u00e7ada \u2013 UPA de Campos Novos, onde detentos t\u00eam a oportunidade de adquirir cultura e educa\u00e7\u00e3o para que ao final do cumprimento de suas penas, possam buscar a ressocializa\u00e7\u00e3o e um t\u00e3o sonhado emprego.<\/p>\n<p style=\"text-align: justify;\">A prova que a educa\u00e7\u00e3o \u00e9 fundamental para a vida das pessoas foi vista no dia 1o de setembro, quando o Conselho da Comunidade, Secretaria de Estado de Educa\u00e7\u00e3o, por meio do Centro de Educa\u00e7\u00e3o de Jovens e Adultos \u2013 CEJA, e dire\u00e7\u00e3o da UPA, realizaram a entrega dos Certificados de Conclus\u00e3o das S\u00e9ries Iniciais (1o ao 5o ano) para oito alunos\/detentos que durante o primeiro semestre do ano, estiveram por tr\u00eas horas todos os dias, obtendo conhecimento de nivelamento educacional.<\/p>\n<p style=\"text-align: justify;\">De acordo com a Professora que coordenou o nivelamento destes alunos\/detentos, S\u00f4nia Aparecida Gon\u00e7alves Thibes, durante todo o semestre, a dedica\u00e7\u00e3o dos alunos foi exemplar. &#8220;Foi um desafio grande trabalhar com os jovens e muito positivo, pois eles demonstraram sempre o interesse pelo aprendizado e isso vai ajudar muito l\u00e1 fora n\u00e3o s\u00f3 no emprego, mas na ressocializa\u00e7\u00e3o em sociedade&#8221;, comentou. Para o Diretor da UPA, Evalcir Morais, os detentos est\u00e3o de parab\u00e9ns por participar do projeto. &#8220;A iniciativa do Conselho da Comunidade e CEJA, contou com nosso apoio e agora os resultados come\u00e7am a ser colhidos. N\u00f3s inicialmente passamos nas celas buscando aqueles que tinham interesse e esses oito alunos conseguiram concluir esta etapa e o projeto continua. Todos que est\u00e3o estudando mudaram sua forma de agir dentro da Unidade, n\u00e3o s\u00f3 pela remi\u00e7\u00e3o de pena, mas tamb\u00e9m por obter conhecimento e muitos desejam quando sair, conseguir um emprego melhor&#8221;, comentou.<\/p>\n<p style=\"text-align: justify;\">Segundo o Presidente do Conselho da Comunidade, Thiago Almeida da Costa, esta primeira turma de formandos \u00e9 uma demonstra\u00e7\u00e3o efetiva de que as a\u00e7\u00f5es do conselho buscam uma melhor qualidade de vida \u00e0s pessoas. &#8220;N\u00f3s do Conselho da Comunidade se sentimos orgulhosos, pois a sala de aula foi custeada pelo conselho e firmamos o conv\u00eanio com o estado, ent\u00e3o para o conselho este trabalho est\u00e1 dando frutos, pois o pessoal est\u00e1 tendo acesso \u00e0 educa\u00e7\u00e3o dentro da Unidade Prisional e isso s\u00f3 engrandece e gera mais motiva\u00e7\u00e3o aos membros do conselho para que possamos desenvolver outros projetos que tragam benef\u00edcios \u00e0 comunidade&#8221;, destacou Thiago.<\/p>\n<p style=\"text-align: justify;\">Com a participa\u00e7\u00e3o e desempenho na atividade educacional, os condenados tem remi\u00e7\u00e3o da pena, assim o condenado diminui o tempo de dura\u00e7\u00e3o de sua pena imposta em senten\u00e7a. A contagem de tempo \u00e9 de um dia a menos de pena a cada doze horas de frequ\u00eancia escolar.<\/p>\n<p style=\"text-align: justify;\"><strong>Biblioteca na UPA<\/strong><\/p>\n<p style=\"text-align: justify;\">O Conselho da Comunidade est\u00e1 buscando tamb\u00e9m instalar uma Biblioteca na Unidade Prisional Avan\u00e7ada \u2013 UPA. Segundo o presidente do Conselho Thiago Almeida da Costa, com isso, todos ter\u00e3o acesso \u00e0 leitura, pois cultura e conhecimento nunca s\u00e3o demais. \u201cN\u00f3s j\u00e1 recebemos alguns livros da Casa da Cultura e Biblioteca Municipal e faremos uma triagem destes exemplares e ap\u00f3s isso, estaremos construindo com a Unidade Prisional, umas prateleiras para armazenar estes livros para garantir o acesso dos apenados\u201d, informou. Thiago destacou ainda que em outros pres\u00eddios, j\u00e1 existe o projeto da biblioteca e a ideia \u00e9 implantar em Campos Novos e discutir literatura com os detentos, como j\u00e1 acontece em outras unidades prisionais.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p>Cr\u00e9ditos:<\/p>\n<p><strong>Jornal O Celeiro &#8211; Campos Novos<\/strong><\/p>\n<p>Reportagem: Felipe G\u00f6tz<\/p>\n<p>Fotografia: Felipe G\u00f6tz<\/p>\n<p>Editora chefe: Antonia Claudete Martins<\/p>","protected":false},"excerpt":{"rendered":"<p>N\u00e3o h\u00e1 barreiras para a educa\u00e7\u00e3o e nenhum impedimento pode interferir na busca pelo conhecimento. A prova de que a educa\u00e7\u00e3o supera todos os obst\u00e1culos \u00e9 difundida na Unidade Prisional Avan\u00e7ada \u2013 UPA de Campos Novos, onde detentos t\u00eam a oportunidade de adquirir cultura e educa\u00e7\u00e3o para que ao final do cumprimento de suas penas, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":14497,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 05:42:00","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13429"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=13429"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13429\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/14497"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=13429"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=13429"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=13429"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}