{"id":13439,"date":"2015-04-28T18:46:53","date_gmt":"2015-04-28T21:46:53","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2015\/04\/28\/diretor-do-deap-recebe-representantes-das-organizacoes-sociais-de-rio-do-sul\/"},"modified":"2023-07-13T17:53:21","modified_gmt":"2023-07-13T20:53:21","slug":"diretor-do-deap-recebe-representantes-das-organizacoes-sociais-de-rio-do-sul","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/diretor-do-deap-recebe-representantes-das-organizacoes-sociais-de-rio-do-sul\/","title":{"rendered":"Diretor do Deap recebe representantes das organiza\u00e7\u00f5es sociais de Rio do Sul"},"content":{"rendered":"<p>O Diretor do Deap, Edemir Alexandre Camargo Neto, recebeu na tarde desta ter\u00e7a-feira (28) representantes do Conselho da Comunidade da Comarca de Rio do Sul, da OAB e empres\u00e1rios da regi\u00e3o para discutir sobre a interdi\u00e7\u00e3o do Pres\u00eddio Regional de Rio do Sul. Durante o encontro foram discutidas quest\u00f5es sobre as atividades laborais desenvolvidas na unidade, poss\u00edveis melhorias estruturais e parcerias entre as institui\u00e7\u00f5es.<\/p>\n<p>Estiveram presentes na reuni\u00e3o al\u00e9m de Edemir Alexandre, os senhores Victor Fontes e Rosandro Schauffler da OAB, a presidente do conselho da comunidade de Rio do Sul Jane Coninck Liz, os empres\u00e1rios Joel da Silva e Denilson Silva e o Sr. Marcos Leandro da Associa\u00e7\u00e3o Comercial Industrial de Rio do Sul.<\/p>","protected":false},"excerpt":{"rendered":"<p>O Diretor do Deap, Edemir Alexandre Camargo Neto, recebeu na tarde desta ter\u00e7a-feira (28) representantes do Conselho da Comunidade da Comarca de Rio do Sul, da OAB e empres\u00e1rios da regi\u00e3o para discutir sobre a interdi\u00e7\u00e3o do Pres\u00eddio Regional de Rio do Sul. Durante o encontro foram discutidas quest\u00f5es sobre as atividades laborais desenvolvidas na [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":14595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 06:01:06","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13439"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=13439"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/14595"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=13439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=13439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=13439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}