{"id":13468,"date":"2021-06-08T20:48:12","date_gmt":"2021-06-08T20:48:12","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2021\/06\/08\/upa-de-sao-miguel-do-oeste-tem-novo-gestor\/"},"modified":"2021-06-08T20:48:12","modified_gmt":"2021-06-08T20:48:12","slug":"upa-de-sao-miguel-do-oeste-tem-novo-gestor","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/upa-de-sao-miguel-do-oeste-tem-novo-gestor\/","title":{"rendered":"UPA de S\u00e3o Miguel do Oeste tem novo gestor"},"content":{"rendered":"<\/p>\n<p>O Departamento de Administra\u00e7\u00e3o Prisional (Deap) informa que o Policial Penal Rodrigo Previatti \u00e9 o novo gestor da UPA de S\u00e3o Miguel do Oeste e o Policial Penal, Gilvani Gutz Pagliari, \u00e9 o chefe de seguran\u00e7a. A SAP agradece aos policias penais Andr\u00e9 Paulo Barea de Oliveira e M\u00e1rcio Adriano Fran\u00e7ozi pelos relevantes servi\u00e7os prestados \u00e0 frente da unidade ao mesmo tempo que deseja sucesso aos novos gestores.<\/p>","protected":false},"excerpt":{"rendered":"<p>O Departamento de Administra\u00e7\u00e3o Prisional (Deap) informa que o Policial Penal Rodrigo Previatti \u00e9 o novo gestor da UPA de S\u00e3o Miguel do Oeste e o Policial Penal, Gilvani Gutz Pagliari, \u00e9 o chefe de seguran\u00e7a. A SAP agradece aos policias penais Andr\u00e9 Paulo Barea de Oliveira e M\u00e1rcio Adriano Fran\u00e7ozi pelos relevantes servi\u00e7os prestados [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1661,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 09:23:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13468"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=13468"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13468\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/1661"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=13468"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=13468"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=13468"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}