{"id":13485,"date":"2021-08-12T17:44:16","date_gmt":"2021-08-12T17:44:16","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2021\/08\/12\/comandante-da-bafl-acompanha-instrucao-ministrada-por-policiais-penais-aos-integrantes-do-estagio-de-policia-aeronautica\/"},"modified":"2021-08-12T17:44:16","modified_gmt":"2021-08-12T17:44:16","slug":"comandante-da-bafl-acompanha-instrucao-ministrada-por-policiais-penais-aos-integrantes-do-estagio-de-policia-aeronautica","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/comandante-da-bafl-acompanha-instrucao-ministrada-por-policiais-penais-aos-integrantes-do-estagio-de-policia-aeronautica\/","title":{"rendered":"Comandante da BAFL acompanha instru\u00e7\u00e3o ministrada por Policiais Penais aos integrantes do Est\u00e1gio de Pol\u00edcia Aeron\u00e1utica"},"content":{"rendered":"<\/p>\n<p>O Secret\u00e1rio da SAP, Leandro Lima, o Secret\u00e1rio Adjunto Edemir Alexandre Camargo Neto e o Diretor da Acaps, Paulo Roberto de Oliveira receberam nesta ter\u00e7a-feira (10) o Tenente-Coronel Aviador Ricardo Felzcky, Comandante da Base A\u00e9rea de Florian\u00f3polis (BAFL), no Centro T\u00e1tico Operacional 01 (CTTOP), localizado no Complexo Penitenci\u00e1rio do Estado, em S\u00e3o Pedro de Alc\u00e2ntara. O&nbsp;Comandante da BAFL foi acompanhar instru\u00e7\u00e3o ministrada pelos Policiais Penais, da Academia de Administra\u00e7\u00e3o Prisional e Socioeducativa, aos integrantes do Est\u00e1gio de Pol\u00edcia Aeron\u00e1utica e conhecer a estrutura do CTTOP.<\/p>","protected":false},"excerpt":{"rendered":"<p>O Secret\u00e1rio da SAP, Leandro Lima, o Secret\u00e1rio Adjunto Edemir Alexandre Camargo Neto e o Diretor da Acaps, Paulo Roberto de Oliveira receberam nesta ter\u00e7a-feira (10) o Tenente-Coronel Aviador Ricardo Felzcky, Comandante da Base A\u00e9rea de Florian\u00f3polis (BAFL), no Centro T\u00e1tico Operacional 01 (CTTOP), localizado no Complexo Penitenci\u00e1rio do Estado, em S\u00e3o Pedro de Alc\u00e2ntara. [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1705,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:53:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13485"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=13485"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1705"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=13485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=13485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=13485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}