{"id":13489,"date":"2021-08-24T16:08:16","date_gmt":"2021-08-24T16:08:16","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2021\/08\/24\/mais-de-2-1-mil-presos-comecam-a-receber-treinamento-para-trabalhar-na-industria-textil\/"},"modified":"2021-08-24T16:08:16","modified_gmt":"2021-08-24T16:08:16","slug":"mais-de-2-1-mil-presos-comecam-a-receber-treinamento-para-trabalhar-na-industria-textil","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/mais-de-2-1-mil-presos-comecam-a-receber-treinamento-para-trabalhar-na-industria-textil\/","title":{"rendered":"Mais de 2,1 mil presos come\u00e7am a receber treinamento para trabalhar na ind\u00fastria t\u00eaxtil"},"content":{"rendered":"<\/p>\n<p>Mais de 2,1 mil apenados come\u00e7aram nesta segunda-feira, 23, a frequentar os cursos profissionalizantes para atuar na ind\u00fastria t\u00eaxtil que est\u00e1 sendo implantada no sistema prisional catarinense. A capacita\u00e7\u00e3o ministrada pelo Senai \u00e9 preparat\u00f3ria para a ativa\u00e7\u00e3o das linhas de produ\u00e7\u00e3o que est\u00e3o sendo montadas nestas unidades. Ao longo dos pr\u00f3ximos 90 dias, os internos receber\u00e3o treinamento para atuar nas \u00e1reas de corte industrial, costura, serigrafia, log\u00edstica e manuten\u00e7\u00e3o de m\u00e1quinas.<\/p>\n<p><a href=\"https:\/\/www.sc.gov.br\/noticias\/temas\/justica-e-defesa-da-cidadania\/governo-e-senai-assinam-convenio-para-capacitar-mais-de-2-mil-detentos-para-trabalho-textil\" target=\"_blank\" rel=\"noopener\">O conv\u00eanio entre Governo do Estado e Senai foi assinado pelo governador Carlos Mois\u00e9s, no \u00faltimo dia 9<\/a>. O investimento do Governo na a\u00e7\u00e3o, incluindo a constru\u00e7\u00e3o de galp\u00f5es e a compra do maquin\u00e1rio, supera os R$ 30 milh\u00f5es.<\/p>\n<p>O treinamento ocorre no Complexo Penitenci\u00e1rio de Chapec\u00f3, Penitenci\u00e1ria Sul, em Crici\u00fama, Penitenci\u00e1ria Industrial de S\u00e3o Crist\u00f3v\u00e3o do Sul, Complexo Penitenci\u00e1rio do Vale do Itaja\u00ed e UPA de S\u00e3o Miguel do Oeste.<\/p>\n<p>O secret\u00e1rio da Administra\u00e7\u00e3o Prisional e Socioeducativa, Leandro Lima, acompanhou o in\u00edcio das atividades em Crici\u00fama e destacou a import\u00e2ncia do projeto. \u201cAo todo vamos gerar cerca de 1,6 mil novas vagas de trabalho qualificado para os apenados, que ser\u00e3o pagos pelo exerc\u00edcio da atividade, sendo que 25% do sal\u00e1rio retorna para o Fundo Rotativo da unidade prisional a t\u00edtulo de indeniza\u00e7\u00e3o. Tamb\u00e9m est\u00e3o sendo constru\u00eddos 18 galp\u00f5es industriais para abrigar as linhas de produ\u00e7\u00e3o. Desta forma com treinamento e infraestrutura adequadas poderemos oferecer produtos de qualidade como, por exemplo, uniformes escolares tanto para a rede p\u00fablica estadual ou municipal\u201d, destacou.<\/p>\n<p>O aumento da oferta de vagas de trabalho tem dois importantes objetivos. O primeiro deles \u00e9 a possibilidade de reabilita\u00e7\u00e3o social e econ\u00f4mica dos internos, com a oferta de treinamento para atuar em atividade qualificada e identificada com a regi\u00e3o. Outro fator importante \u00e9 que 25% do sal\u00e1rio retornam para o Fundo Rotativo e o valor arrecadado \u00e9 totalmente reinvestido na unidade, em obras de infraestrutura ou aquisi\u00e7\u00e3o de equipamentos para a implanta\u00e7\u00e3o de novas oficinas. Al\u00e9m disso, o trabalho \u00e9 uma estrat\u00e9gia de seguran\u00e7a prisional.<\/p>","protected":false},"excerpt":{"rendered":"<p>Mais de 2,1 mil apenados come\u00e7aram nesta segunda-feira, 23, a frequentar os cursos profissionalizantes para atuar na ind\u00fastria t\u00eaxtil que est\u00e1 sendo implantada no sistema prisional catarinense. A capacita\u00e7\u00e3o ministrada pelo Senai \u00e9 preparat\u00f3ria para a ativa\u00e7\u00e3o das linhas de produ\u00e7\u00e3o que est\u00e3o sendo montadas nestas unidades. Ao longo dos pr\u00f3ximos 90 dias, os internos [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1714,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:53:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13489"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=13489"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13489\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1714"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=13489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=13489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=13489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}