{"id":13491,"date":"2021-09-02T17:19:14","date_gmt":"2021-09-02T17:19:14","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2021\/09\/02\/estado-inaugura-primeiro-galpao-do-novo-polo-industrial-textil-do-presidio-feminino-de-chapeco\/"},"modified":"2021-09-02T17:19:14","modified_gmt":"2021-09-02T17:19:14","slug":"estado-inaugura-primeiro-galpao-do-novo-polo-industrial-textil-do-presidio-feminino-de-chapeco","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/estado-inaugura-primeiro-galpao-do-novo-polo-industrial-textil-do-presidio-feminino-de-chapeco\/","title":{"rendered":"Estado inaugura primeiro galp\u00e3o do novo polo industrial t\u00eaxtil do Pres\u00eddio Feminino de Chapec\u00f3"},"content":{"rendered":"<\/p>\n<p>A ativa\u00e7\u00e3o do primeiro galp\u00e3o industrial no Pres\u00eddio Feminino de Chapec\u00f3, nesta quarta-feira, 1\u00ba de setembro, materializa o projeto SAP T\u00eaxtil. Iniciativa do Governo do Estado, por meio da Secretaria de Administra\u00e7\u00e3o Prisional e Socioeducativa (SAP), o projeto prev\u00ea a instala\u00e7\u00e3o de 18 galp\u00f5es nas unidades prisionais localizadas em Chapec\u00f3, Crici\u00fama, Curitibanos, Itaja\u00ed, S\u00e3o Jos\u00e9 do Cedro e S\u00e3o Miguel do Oeste e atende aos prop\u00f3sitos do Programa SC Mais Oportunidade.<\/p>\n<p>Na inaugura\u00e7\u00e3o do espa\u00e7o, o secret\u00e1rio da SAP, Leandro Lima, refor\u00e7ou a import\u00e2ncia de se manter e ampliar as pol\u00edticas de gera\u00e7\u00e3o de emprego e renda para os apenados. &#8220;O SAP T\u00eaxtil existe porque \u00e9 o ramo da ind\u00fastria que mais emprega em Santa Catarina. N\u00f3s estamos capacitando as internas para enfrentar o mercado de trabalho quando deixarem o sistema&#8221;, disse. Leandro Lima destacou que o trabalho de todos os operadores do sistema \u00e9 fundamental para viabilizar os programas de gera\u00e7\u00e3o de emprego e renda em todo o sistema prisional catarinense.<\/p>\n<p>O secret\u00e1rio da SAP fez um agradecimento especial ao governador Carlos Mois\u00e9s. &#8220;O governador tem sido um grande parceiro do sistema prisional e entende que o trabalho de reabilita\u00e7\u00e3o social e econ\u00f4mica do apenado passa pela capacita\u00e7\u00e3o, oferta de vaga de trabalho e dignidade no cumprimento da pena\u201d, finalizou.<\/p>\n<p>Presente na inaugura\u00e7\u00e3o, a diretora-geral do Departamento Penitenci\u00e1rio Nacional (Depen), T\u00e2nia Foga\u00e7a, assinalou que o investimento no sistema prisional \u00e9 investir em seguran\u00e7a p\u00fablica. &#8220;As pol\u00edticas de combate ao crime organizado passam necessariamente pela evolu\u00e7\u00e3o do sistema prisional&#8221;. T\u00e2nia Foga\u00e7a enfatizou que o Minist\u00e9rio da Justi\u00e7a e da Seguran\u00e7a P\u00fablica (MJSP) tem uma vis\u00e3o clara nesse sentido, ou seja, compreende o sistema prisional como potente ferramenta de combate ao crime organizado e que deve ser usada como tal. Ela refor\u00e7ou que o Depen apoiou a oficina rec\u00e9m-inaugurada em Chapec\u00f3 destinando R$ 386 mil para a compra de equipamentos por meio do Procap.<\/p>\n<p>Tamb\u00e9m participaram da solenidade, o secret\u00e1rio adjunto da SAP, Edemir Alexandre Camargo Neto, o diretor do Deap, Vladecir Souza dos Santos, o diretor de Pol\u00edticas Penitenci\u00e1rias do Depen, Sandro Abel Sousa Barradas, entre outros convidados especiais.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-1719\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2021\/09\/estado_inaugura_primeiro_galpao_do_novo_polo_industrial_textil_do_presidio_feminino_de_chapeco__20210901_1307077329-36b.jpeg\" alt=\"estado inaugura primeiro galpao do novo polo industrial textil do presidio feminino de chapeco 20210901 1307077329\" width=\"620\" height=\"463\" \/><\/p>\n<p><strong>Os polos<\/strong><\/p>\n<p>Cada polo industrial em fase de instala\u00e7\u00e3o nas unidades de Crici\u00fama, Curitibanos, Chapec\u00f3, Itaja\u00ed, S\u00e3o Miguel do Oeste e S\u00e3o Jos\u00e9 do Cedro ter\u00e1 linhas de produ\u00e7\u00e3o para a confec\u00e7\u00e3o de uniformes escolares, podendo tamb\u00e9m atender outras demandas como produ\u00e7\u00e3o de enxovais para hospitais.<\/p>\n<p><strong>N\u00fameros<\/strong><\/p>\n<p>O Governo do Estado est\u00e1 investindo cerca de R$ 30 milh\u00f5es na concretiza\u00e7\u00e3o do projeto. Neste momento h\u00e1 cerca de 2,1 mil apenados no estado recebendo treinamento para atuar nas \u00e1reas de corte e costura industrial, serigrafia, manuten\u00e7\u00e3o de m\u00e1quinas e log\u00edstica. Os cursos s\u00e3o ministrados pelo Senai, institui\u00e7\u00e3o do sistema Fiesc, cujo objetivo \u00e9 estimular a inova\u00e7\u00e3o industrial por meio da educa\u00e7\u00e3o, consultoria, pesquisa aplicada e servi\u00e7os t\u00e9cnicos e tecnol\u00f3gicos.<\/p>\n<p>Ap\u00f3s o t\u00e9rmino da capacita\u00e7\u00e3o, com dura\u00e7\u00e3o prevista de 90 dias, o SAP T\u00eaxtil absorver\u00e1 de imediato a m\u00e3o de obra de 1,5 mil apenados. Todos receber\u00e3o sal\u00e1rio, sendo que 25% vai para o Fundo Rotativo da unidade. Os 75% v\u00e3o para o interno. A maioria destina os valores recebidos por meio do trabalho para ajudar na manuten\u00e7\u00e3o da fam\u00edlia.<\/p>\n<p>Este primeiro galp\u00e3o industrial tem 325 metros quadrados, 40 m\u00e1quinas de costura e gera 60 vagas de trabalho exclusivas para mulheres privadas de liberdade do Pres\u00eddio Feminino de Chapec\u00f3. As demais linhas de produ\u00e7\u00e3o em Curitibanos, Crici\u00fama, Itaja\u00ed, S\u00e3o Jos\u00e9 do Cedro e S\u00e3o Miguel do Oeste ser\u00e3o ativadas \u00e0 medida que a constru\u00e7\u00e3o dos galp\u00f5es seja finalizada.<\/p>\n<p><strong>Depen<\/strong><\/p>\n<p>O Depen \u00e9 o \u00f3rg\u00e3o executivo do Minist\u00e9rio da Justi\u00e7a e da Seguran\u00e7a P\u00fablica que acompanha e controla a aplica\u00e7\u00e3o da Lei de Execu\u00e7\u00e3o Penal e das diretrizes da Pol\u00edtica Penitenci\u00e1ria Nacional, emanadas, principalmente, pelo Conselho Nacional de Pol\u00edtica Criminal e Penitenci\u00e1ria. Al\u00e9m disso, o Departamento \u00e9 o gestor do Fundo Penitenci\u00e1rio Nacional.<\/p>","protected":false},"excerpt":{"rendered":"<p>A ativa\u00e7\u00e3o do primeiro galp\u00e3o industrial no Pres\u00eddio Feminino de Chapec\u00f3, nesta quarta-feira, 1\u00ba de setembro, materializa o projeto SAP T\u00eaxtil. Iniciativa do Governo do Estado, por meio da Secretaria de Administra\u00e7\u00e3o Prisional e Socioeducativa (SAP), o projeto prev\u00ea a instala\u00e7\u00e3o de 18 galp\u00f5es nas unidades prisionais localizadas em Chapec\u00f3, Crici\u00fama, Curitibanos, Itaja\u00ed, S\u00e3o Jos\u00e9 [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1718,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:53:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13491"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=13491"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13491\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1718"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=13491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=13491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=13491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}