{"id":13564,"date":"2021-12-30T19:50:51","date_gmt":"2021-12-30T19:50:51","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2021\/12\/30\/sap-investe-r-6-8-milhoes-em-uniformes-para-servidores-do-dpp-e-dease\/"},"modified":"2021-12-30T19:50:51","modified_gmt":"2021-12-30T19:50:51","slug":"sap-investe-r-6-8-milhoes-em-uniformes-para-servidores-do-dpp-e-dease-2","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/sap-investe-r-6-8-milhoes-em-uniformes-para-servidores-do-dpp-e-dease-2\/","title":{"rendered":"SAP investe R$ 6,8 milh\u00f5es em uniformes para servidores do DPP e Dease"},"content":{"rendered":"<\/p>\n<p>O Secret\u00e1rio de Administra\u00e7\u00e3o Prisional e Socioeducativa, Leandro Lima, participou nesta quinta-feira (30) do ato de entrega dos primeiros kits de uniformes para Policiais Penais e Agentes de Seguran\u00e7a Socioeducativa, realizado no Almoxarifado da SAP, em Palho\u00e7a. O investimento da SAP na aquisi\u00e7\u00e3o dos uniformes foi de R$ 6,8 milh\u00f5es.<\/p>\n<p>O material e a modelagem dos uniformes foram definidos por uma equipe de servidores que consideraram necessidades e rotinas dos profissionais que atuam nas unidades prisionais e socioeducativas. Essas informa\u00e7\u00f5es basearam o termo de refer\u00eancia para a realiza\u00e7\u00e3o da licita\u00e7\u00e3o. Al\u00e9m de identificar os profissionais da SAP, os uniformes foram confeccionados em materiais de alta qualidade e durabilidade para garantir o conforto do servidor.<\/p>\n<p>Em seu pronunciamento, Leandro Lima, destacou que este \u00e9 um momento hist\u00f3rico para a SAP. \u201cEssa n\u00e3o foi a primeira entrega de uniformes, foi a \u00fanica na hist\u00f3ria da SAP. Os servidores dos sistema prisional e socioeducativo nunca receberam kit com uniforme completo, com todos os itens totalmente pagos pelo estado\u201d, destacou. Lima refor\u00e7ou a import\u00e2ncia da constru\u00e7\u00e3o da identidade visual da Pol\u00edcia Penal e do Dease e o quanto isso impacta na responsabilidade de cada servidor p\u00fablico. \u201c\u00c9 importante compreender que a entrega do uniforme representa muito mais do que a identifica\u00e7\u00e3o visual, representa a valoriza\u00e7\u00e3o e o reconhecimento do trabalho de cada um de voc\u00eas\u201d, enfatizou. Dentre os investimentos que est\u00e3o sendo feitos, Lima destacou a aquisi\u00e7\u00e3o de 4 mil pistolas da marca Beretta, renova\u00e7\u00e3o da frota e os programas de forma\u00e7\u00e3o e treinamentos oferecidos pela Academia de Administra\u00e7\u00e3o Prisional e Socioeducativa (Acaps). \u201cO SAPCi\u00eancia est\u00e1 oferecendo 650 vagas para cursos de p\u00f3s-gradua\u00e7\u00e3o, mestrado e doutorado e isso nos permite articular o conhecimento da acad\u00eamica com a pr\u00e1tica profissional, tudo pago pelo estado.\u201d<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-1874\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2021\/12\/62b4fd7c-9301-4b38-88e5-8cf3879952c0-fcb.jpg\" alt=\"62b4fd7c 9301 4b38 88e5 8cf3879952c0\" width=\"1280\" height=\"854\" \/><\/p>\n<p>Outro ponto enfatizado pelo Secret\u00e1rio da SAP foi o papel fundamental desempenhado pela equipe da Diretoria de Administra\u00e7\u00e3o e Finan\u00e7as (Diaf). \u201cPara que a coisa aconte\u00e7a \u00e9 preciso ter recursos financeiros e n\u00f3s conseguimos viabilizar uma s\u00e9rie de investimentos porque houve a revis\u00e3o e renegocia\u00e7\u00e3o de contratos e toda essa economia est\u00e1 sendo revertida na compra de viaturas, de armas, na moderniza\u00e7\u00e3o do parque tecnol\u00f3gico, no aumento da rede de internet, entre outras a\u00e7\u00f5es\u201d.<\/p>\n<p>Ele tamb\u00e9m elogiou o trabalho desenvolvido pela equipe da Ger\u00eancia de Patrim\u00f4nio (Gepat). \u201cDesde mar\u00e7o do ano passado, a Gepat vem se desdobrando para atender \u00e0s demandas da pandemia sem comprometer \u00e0s necessidades de rotina dos sistemas\u201d, disse, lembrando que nos pr\u00f3ximos dias, a Gepat come\u00e7ar\u00e1 gradualmente a enviar os uniformes para todas as unidades prisionais e socioeducativas.<\/p>\n<p>O secret\u00e1rio adjunto da SAP, Edemir Alexandre Camargo Neto, destacou que para se chegar at\u00e9 o momento de entrega de um equipamento, h\u00e1 diversas \u00e1reas envolvidas. \u201cEsses setores que s\u00e3o invis\u00edveis para a maioria s\u00e3o fundamentais para a concretiza\u00e7\u00e3o de investimentos importantes\u201d, disse o Secret\u00e1rio Adjunto. \u201cA institui\u00e7\u00e3o est\u00e1 em cada um de n\u00f3s\u201d.<\/p>\n<p>O Diretor de Administra\u00e7\u00e3o e Finan\u00e7as da SAP, Bruno Gabriel, manifestou orgulho pela entrega do kit de uniformes. \u201c\u00c9 o reconhecimento pelo trabalho silencioso da Gelic e de toda a equipe da Diaf, da Comiss\u00e3o de profissionais que definiu os uniformes de acordo com a demanda do servidor, buscando o melhor pre\u00e7o, sem comprometer a qualidade do que est\u00e1 sendo entregue\u201d, finalizou.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-1875\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2021\/12\/9129dd3d-de6d-44ed-8df5-51b22c1bddb7-98d.jpg\" alt=\"9129dd3d de6d 44ed 8df5 51b22c1bddb7\" width=\"1280\" height=\"854\" \/><\/p>\n<p>Cada kit de uniforme cont\u00e9m cal\u00e7a t\u00e1tica (02); camisa t\u00e1tica (02); camiseta (02), bon\u00e9 com logotipo (01); cinto t\u00e1tico (01), jaqueta imperme\u00e1vel (01) e bota t\u00e1tica com cano curto (01).<\/p>\n<p>Tamb\u00e9m participaram do ato de entrega o Diretor-geral do DPP, Vladecir dos Santos; o Diretor-geral do Dease, Zeno Tressoldi; o Diretor de Intelig\u00eancia, Ricardo Ferreira; Diretor da Acaps, Paulo Roberto de Oliveira, o Coordenador de Opera\u00e7\u00f5es do DPP, Robson Oliveira; os Superintendentes das Regionais Norte, Juliano Stroebel e da Grande Florian\u00f3polis, Claudiomiro Luiz Marques; o Diretor do COPE, Thanael Hoenicke, al\u00e9m de Policiais Penais e Agentes de Seguran\u00e7a Socioeducativos.<\/p>","protected":false},"excerpt":{"rendered":"<p>O Secret\u00e1rio de Administra\u00e7\u00e3o Prisional e Socioeducativa, Leandro Lima, participou nesta quinta-feira (30) do ato de entrega dos primeiros kits de uniformes para Policiais Penais e Agentes de Seguran\u00e7a Socioeducativa, realizado no Almoxarifado da SAP, em Palho\u00e7a. O investimento da SAP na aquisi\u00e7\u00e3o dos uniformes foi de R$ 6,8 milh\u00f5es. O material e a modelagem [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1873,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:17:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13564"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=13564"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13564\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1873"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=13564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=13564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=13564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}