{"id":13568,"date":"2022-01-11T18:15:24","date_gmt":"2022-01-11T18:15:24","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2022\/01\/11\/penitenciaria-da-regiao-de-curitibanos-faz-a-primeira-colheita-de-mel-de-2022\/"},"modified":"2022-01-11T18:15:24","modified_gmt":"2022-01-11T18:15:24","slug":"penitenciaria-da-regiao-de-curitibanos-faz-a-primeira-colheita-de-mel-de-2022","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/penitenciaria-da-regiao-de-curitibanos-faz-a-primeira-colheita-de-mel-de-2022\/","title":{"rendered":"Penitenci\u00e1ria da Regi\u00e3o de Curitibanos faz a primeira colheita de mel de 2022"},"content":{"rendered":"<\/p>\n<p>Localizada em S\u00e3o Crist\u00f3v\u00e3o do Sul, a Penitenci\u00e1ria da Regi\u00e3o de Curitibanos acaba de realizar a sua primeira colheita de mel, em 2022. Ao todo foram colhidos aproximadamente 250 quilos do produto, extra\u00eddos de 35 caixas colmeias. Toda a produ\u00e7\u00e3o \u00e9 resultado das atividades de apicultura desenvolvidas pelos detentos na unidade por meio do Fundo Rotativo da Penitenci\u00e1ria da Regi\u00e3o de Curitibanos. \u201cAl\u00e9m de promover a reabilita\u00e7\u00e3o social dos apenados e a remi\u00e7\u00e3o da pena, a atividade tamb\u00e9m gera receitas com a finalidade de restituir o Estado, raz\u00e3o pela qual, durante a semana ser\u00e1 instalado mais 40 caixas colmeias com o intuito de aumentar a produ\u00e7\u00e3o\u201d, observou o Diretor da Penitenci\u00e1ria, Jair Ant\u00f4nio Fran\u00e7a.<\/p>\n<p>Para o Secret\u00e1rio de Administra\u00e7\u00e3o Prisional e Socioeducativa, Leandro Lima, outro ponto que merece ser destacado \u00e9 o empreendedorismo que crescendo nos Fundos Rotativos Regionais. \u201c\u00c9 muito importante que as unidades comecem a empreender, assim manteremos nossas pol\u00edticas laborais cada vez mais s\u00f3lidas\u201d, enfatizou.<br \/>Toda a produ\u00e7\u00e3o estar\u00e1 dispon\u00edvel para venda em recipientes de 250 gramas, 500 gramas e 1 quilo, na Feirinha da unidade, sempre das 12h \u00e0s 19h. Informa\u00e7\u00f5es poder\u00e3o ser obtidas pelo telefone da Ger\u00eancia de Atividades Laborais (49) 3412-3284.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-1883\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2022\/01\/colheita_de_mel_de_2022_2-bc3.jpeg\" alt=\"colheita de mel de 2022 2\" width=\"958\" height=\"684\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>Localizada em S\u00e3o Crist\u00f3v\u00e3o do Sul, a Penitenci\u00e1ria da Regi\u00e3o de Curitibanos acaba de realizar a sua primeira colheita de mel, em 2022. Ao todo foram colhidos aproximadamente 250 quilos do produto, extra\u00eddos de 35 caixas colmeias. Toda a produ\u00e7\u00e3o \u00e9 resultado das atividades de apicultura desenvolvidas pelos detentos na unidade por meio do Fundo [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1882,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 07:30:18","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13568"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=13568"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13568\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1882"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=13568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=13568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=13568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}