{"id":13662,"date":"2022-11-18T13:41:02","date_gmt":"2022-11-18T13:41:02","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2022\/11\/18\/fuga17-11\/"},"modified":"2022-11-18T13:41:02","modified_gmt":"2022-11-18T13:41:02","slug":"fuga17-11","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/fuga17-11\/","title":{"rendered":"NOTA OFICIAL"},"content":{"rendered":"<\/p>\n<p>O Departamento de Pol\u00edcia Penal (DPP) informa que nesta quinta-feira (17), por volta das 16h, um interno do regime semiaberto da Penitenci\u00e1ria da Capital empreendeu fuga, enquanto estava trabalhando.<\/p>\n<p>Todas as medidas legais e periciais j\u00e1 foram tomadas para apurar as circunst\u00e2ncias da fuga e responsabilidades.<\/p>","protected":false},"excerpt":{"rendered":"<p>O Departamento de Pol\u00edcia Penal (DPP) informa que nesta quinta-feira (17), por volta das 16h, um interno do regime semiaberto da Penitenci\u00e1ria da Capital empreendeu fuga, enquanto estava trabalhando. Todas as medidas legais e periciais j\u00e1 foram tomadas para apurar as circunst\u00e2ncias da fuga e responsabilidades.<\/p>","protected":false},"author":8,"featured_media":2003,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 05:58:03","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13662"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=13662"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13662\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/2003"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=13662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=13662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=13662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}