{"id":13675,"date":"2022-12-15T19:09:19","date_gmt":"2022-12-15T19:09:19","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2022\/12\/15\/internas-do-presidio-feminino-de-joinville-recebem-capacitacao-para-trabalhar-no-ramo-da-beleza\/"},"modified":"2022-12-15T19:09:19","modified_gmt":"2022-12-15T19:09:19","slug":"internas-do-presidio-feminino-de-joinville-recebem-capacitacao-para-trabalhar-no-ramo-da-beleza-2","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/internas-do-presidio-feminino-de-joinville-recebem-capacitacao-para-trabalhar-no-ramo-da-beleza-2\/","title":{"rendered":"Internas do Pres\u00eddio Feminino de Joinville recebem capacita\u00e7\u00e3o para trabalhar no ramo da beleza"},"content":{"rendered":"<\/p>\n<p>Oferecer capacita\u00e7\u00e3o profissional para homens e mulheres privados de liberdade \u00e9 uma das premissas do sistema prisional catarinense. Dentro desta filosofia, o Pres\u00eddio Feminino de Joinville (PFJ), em parceria com o empres\u00e1rio do ramo da beleza, Alexandre Simas, desenvolveu o projeto Germinar, uma forma\u00e7\u00e3o que permite \u00e0s internas atuar como designers de sobrancelha. Para marcar a conclus\u00e3o do curso, foi realizada uma cerim\u00f4nia de formatura coma entrega da certifica\u00e7\u00e3o.<\/p>\n<p>Conforme a Diretora do PFJ, Elaine Ribeiro Lampe, as internas rec\u00e9m-formadas devem progredir para o regime semiaberto em um per\u00edodo de 1 (um) ano. Desta forma poder\u00e3o trabalhar no ramo da beleza durante o dia e retornar para a unidade prisional no per\u00edodo noturno. Na solenidade de formatura, al\u00e9m do certificado, as internas receberam kits com materiais para iniciar na nova profiss\u00e3o.<\/p>","protected":false},"excerpt":{"rendered":"<p>Oferecer capacita\u00e7\u00e3o profissional para homens e mulheres privados de liberdade \u00e9 uma das premissas do sistema prisional catarinense. Dentro desta filosofia, o Pres\u00eddio Feminino de Joinville (PFJ), em parceria com o empres\u00e1rio do ramo da beleza, Alexandre Simas, desenvolveu o projeto Germinar, uma forma\u00e7\u00e3o que permite \u00e0s internas atuar como designers de sobrancelha. Para marcar [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":2109,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 05:42:44","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13675"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=13675"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13675\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2109"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=13675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=13675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=13675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}