{"id":13676,"date":"2022-12-15T19:11:41","date_gmt":"2022-12-15T19:11:41","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2022\/12\/15\/presidio-feminino-de-joinville-trabalha-arte-como-forma-de-reintegracao-social\/"},"modified":"2022-12-15T19:11:41","modified_gmt":"2022-12-15T19:11:41","slug":"presidio-feminino-de-joinville-trabalha-arte-como-forma-de-reintegracao-social-2","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/presidio-feminino-de-joinville-trabalha-arte-como-forma-de-reintegracao-social-2\/","title":{"rendered":"Pres\u00eddio Feminino de Joinville trabalha arte como forma de reintegra\u00e7\u00e3o social"},"content":{"rendered":"<\/p>\n<p>A arte como forma de reintegra\u00e7\u00e3o social \u00e9 o tema da primeira exposi\u00e7\u00e3o art\u00edstica do Pres\u00eddio Feminino de Joinville. A mostra resultou do trabalho desenvolvido pelas professoras de arte do Centro de Educa\u00e7\u00e3o de Jovens e Adultos (Ceja), da Rede Estadual de Ensino do Estado de Santa Catarina, em Joinville. <br \/>A exposi\u00e7\u00e3o \u00e9 composta por trabalhos de expressionismo, perspectiva e composi\u00e7\u00e3o visual, por meio de releituras de obras de artistas renomados, de Van Gogh a Romero Brito, utilizando uma variedade de mat\u00e9rias-primas, inclusive, recicl\u00e1veis. <br \/>\u201cO objetivo, al\u00e9m de seguir a Lei de Diretrizes e Bases (LDB), e a Base Nacional Comum Curricular (BNCC), foi levar, e ensinar, a arte de um jeito mais leve, despertando o interesse nas alunas sobre os conceitos e as mais variadas express\u00f5es art\u00edsticas\u201d, destacou a professora de arte, Josiane Marcondes Brand\u00e3o, respons\u00e1vel pela mostra.<\/p>","protected":false},"excerpt":{"rendered":"<p>A arte como forma de reintegra\u00e7\u00e3o social \u00e9 o tema da primeira exposi\u00e7\u00e3o art\u00edstica do Pres\u00eddio Feminino de Joinville. A mostra resultou do trabalho desenvolvido pelas professoras de arte do Centro de Educa\u00e7\u00e3o de Jovens e Adultos (Ceja), da Rede Estadual de Ensino do Estado de Santa Catarina, em Joinville. A exposi\u00e7\u00e3o \u00e9 composta por [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":2111,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 05:42:54","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13676"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=13676"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/13676\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2111"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=13676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=13676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=13676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}