{"id":14993,"date":"2021-09-17T19:49:48","date_gmt":"2021-09-17T19:49:48","guid":{"rendered":"http:\/\/webacaps2023migra.intranet.ciasc.gov.br\/2021\/09\/17\/topp-xi-convocacao-para-taf\/"},"modified":"2021-09-17T19:49:48","modified_gmt":"2021-09-17T19:49:48","slug":"topp-xi-convocacao-para-taf","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/topp-xi-convocacao-para-taf\/","title":{"rendered":"TOPP XI &#8211; Convoca\u00e7\u00e3o para TAF"},"content":{"rendered":"<\/p>\n<p>Considerando as especificidades publicadas no INFORMATIVO 001\/2021\/ACAPS referente ao CURSO DE T\u00c9CNICAS OPERACIONAIS DE POLICIA PENAL \u2013 Turma 11;<\/p>\n<p>&nbsp;A&nbsp;Acaps comunica que houve um total de inscri\u00e7\u00f5es de 129 servidores da SAP e 6 de outros Estados e institui\u00e7\u00f5es coirm\u00e3s;<\/p>\n<p>Dando continuidade ao Processo de Distribui\u00e7\u00e3o de Vagas convocam-se os part\u00edcipes a apresentarem-se no dia 20 de setembro de 2021 para a realiza\u00e7\u00e3o do Teste de Aptid\u00e3o F\u00edsica conforme as seguintes instru\u00e7\u00f5es:<\/p>\n<p>Apresentar-se com traje adequado para a pr\u00e1tica de atividades f\u00edsicas e munido dos seguintes documentos:<\/p>\n<ol style=\"list-style-type: lower-alpha;\">\n<li>Identidade funcional;<\/li>\n<li>Atestado m\u00e9dico original, leg\u00edvel, expedido em data m\u00e1xima retroativa a 30 dias da realiza\u00e7\u00e3o do TAF informando que o aluno est\u00e1 apto a realizar atividades f\u00edsicas.<\/li>\n<\/ol>\n<p><strong>Local:<\/strong><\/p>\n<p>Escola de Aprendizes Marinheiros de Santa Catarina &#8211; Endere\u00e7o: Av. Marinheiro Max Schramm, 3028 &#8211; Jardim Atl\u00e2ntico, Florian\u00f3polis &#8211; SC, 88095-900;<\/p>\n<p>N\u00e3o haver\u00e1 disponibilidade de estacionamento no local, ficando a cargo do aluno estacionar e deslocar-se para o TAF;<\/p>\n<p><strong>O TAF ocorrer\u00e1 das 8h \u00e0s 18h;<\/strong><\/p>\n<p>O aluno dever\u00e1 apresentar-se com <strong>anteced\u00eancia de 15min<\/strong> do in\u00edcio do seu TAF;<\/p>\n<p>Dados ao quantitativo de inscritos foram divididos em quatro turmas de hor\u00e1rios conforme rela\u00e7\u00e3o anexo:<\/p>\n<p><a class=\"doclink\" href=\"index.php?option=com_docman&amp;view=document&amp;alias=127--7&amp;category_slug=normativas&amp;Itemid=291\">Convoca\u00e7\u00e3o_TAF_TOPP_XI<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Considerando as especificidades publicadas no INFORMATIVO 001\/2021\/ACAPS referente ao CURSO DE T\u00c9CNICAS OPERACIONAIS DE POLICIA PENAL \u2013 Turma 11; &nbsp;A&nbsp;Acaps comunica que houve um total de inscri\u00e7\u00f5es de 129 servidores da SAP e 6 de outros Estados e institui\u00e7\u00f5es coirm\u00e3s; Dando continuidade ao Processo de Distribui\u00e7\u00e3o de Vagas convocam-se os part\u00edcipes a apresentarem-se no dia [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1315],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:49:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/14993"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=14993"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/14993\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=14993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=14993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=14993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}