{"id":15005,"date":"2021-10-28T17:32:27","date_gmt":"2021-10-28T17:32:27","guid":{"rendered":"http:\/\/webacaps2023migra.intranet.ciasc.gov.br\/2021\/10\/28\/aprovada-a-lei-que-cria-a-policia-penal-em-santa-catarina\/"},"modified":"2021-10-28T17:32:27","modified_gmt":"2021-10-28T17:32:27","slug":"aprovada-a-lei-que-cria-a-policia-penal-em-santa-catarina","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/aprovada-a-lei-que-cria-a-policia-penal-em-santa-catarina\/","title":{"rendered":"Aprovada a lei que cria a Pol\u00edcia Penal em Santa Catarina"},"content":{"rendered":"<\/p>\n<p>Dia hist\u00f3rico! ???<\/p>\n<p>Aprovada lei que cria a pol\u00edcia penal no Estado de Santa Catarina.<\/p>\n<p>Nesta quarta-feira, dia 28, foi aprovado o projeto de Lei Complementar que cria a Pol\u00edcia Penal de Santa Catarina, bem como seu Estatuto, o qual apresenta todas as especificidades da carreira.<\/p>\n<p>O secret\u00e1rio de Estado de Administra\u00e7\u00e3o Prisional e Socioeducativa, Leandro Lima, celebrou a aprova\u00e7\u00e3o que, na sua avalia\u00e7\u00e3o, \u201cpermitir\u00e1 a Santa Catarina ter a Pol\u00edcia Penal mais moderna do pa\u00eds, destacando que a legisla\u00e7\u00e3o atende aos desafios mais prementes de enfrentamento ao crime organizado, estabelecendo pol\u00edticas de ressocializa\u00e7\u00e3o, al\u00e9m de avan\u00e7ar na valoriza\u00e7\u00e3o desses servidores p\u00fablicos\u201d.<\/p>\n<p>A Academia de Administra\u00e7\u00e3o Prisional e Socioeducativa manifesta sua m\u00e1xima alegria com o in\u00edcio dessa nova era, e continuar\u00e1 n\u00e3o medindo esfor\u00e7os para que os policiais penais catarinenses sejam constantemente qualificados e atualizados, fator que refletir\u00e1 n\u00e3o somente no sistema prisional, mas em toda sociedade.<\/p>\n<p>Parab\u00e9ns a todos por essa vit\u00f3ria!<\/p>","protected":false},"excerpt":{"rendered":"<p>Dia hist\u00f3rico! ??? Aprovada lei que cria a pol\u00edcia penal no Estado de Santa Catarina. Nesta quarta-feira, dia 28, foi aprovado o projeto de Lei Complementar que cria a Pol\u00edcia Penal de Santa Catarina, bem como seu Estatuto, o qual apresenta todas as especificidades da carreira. O secret\u00e1rio de Estado de Administra\u00e7\u00e3o Prisional e Socioeducativa, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":141,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1315],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:50:46","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/15005"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=15005"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/15005\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=15005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=15005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=15005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}