{"id":15057,"date":"2022-03-25T22:01:09","date_gmt":"2022-03-25T22:01:09","guid":{"rendered":"http:\/\/webacaps2023migra.intranet.ciasc.gov.br\/2022\/03\/25\/resultado-final-do-processo-de-credenciamento\/"},"modified":"2022-03-25T22:01:09","modified_gmt":"2022-03-25T22:01:09","slug":"resultado-final-do-processo-de-credenciamento","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/resultado-final-do-processo-de-credenciamento\/","title":{"rendered":"Resultado Final do Processo de Credenciamento"},"content":{"rendered":"<\/p>\n<p>Confira (abaixo) o <strong>RESULTADO FINAL<\/strong> do Processo de Credenciamento e Sele\u00e7\u00e3o de Servidor Docente para compor o corpo docente da Academia de Administra\u00e7\u00e3o Prisional e Socioeducativa &#8211; Acaps da Secretaria de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa &#8211; SAP &#8211; Edital 001\/2022\/ACAPS\/SAP.<\/p>\n<p>Resultado Final <a href=\"\/en\/documentos\/normativas\/194-resultado-final-processo-de-credenciemento\/\">(Clique Aqui)<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Confira (abaixo) o RESULTADO FINAL do Processo de Credenciamento e Sele\u00e7\u00e3o de Servidor Docente para compor o corpo docente da Academia de Administra\u00e7\u00e3o Prisional e Socioeducativa &#8211; Acaps da Secretaria de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa &#8211; SAP &#8211; Edital 001\/2022\/ACAPS\/SAP. Resultado Final (Clique Aqui).<\/p>","protected":false},"author":6,"featured_media":242,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1315],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 07:07:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/15057"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=15057"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/15057\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=15057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=15057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=15057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}