{"id":15781,"date":"2023-11-29T14:45:30","date_gmt":"2023-11-29T17:45:30","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/?p=15781"},"modified":"2023-12-15T14:44:45","modified_gmt":"2023-12-15T17:44:45","slug":"camara-de-vereadores-de-mafra-homenageia-agentes-de-seguranca-socioeducativos","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/camara-de-vereadores-de-mafra-homenageia-agentes-de-seguranca-socioeducativos\/","title":{"rendered":"C\u00e2mara de Vereadores de Mafra homenageia agentes de seguran\u00e7a socioeducativos"},"content":{"rendered":"<p>Recentemente, os agentes de seguran\u00e7a socioeducativos Marcelo Zaranski e Emanuel de Barros, lotados no CASE Regional de Joinville, foram homenageados pela C\u00e2mara de Vereadores de Mafra devido \u00e0 sua destacada atua\u00e7\u00e3o em um atendimento de emerg\u00eancia ocorrido em 3 de outubro na BR 101, pr\u00f3ximo a Itaja\u00ed, envolvendo uma v\u00edtima de acidente de tr\u00e2nsito.<\/p>\n<p>No momento do incidente, ambos se depararam com uma colis\u00e3o grave entre uma camionete e uma motocicleta, resultando no arremesso da ocupante da motocicleta para a rodovia. Agindo com coragem, benevol\u00eancia e rapidez, os servidores prestaram os primeiros socorros \u00e0 v\u00edtima e sinalizaram o local do acidente, evitando transtornos adicionais ao tr\u00e2nsito intenso na \u00e1rea, at\u00e9 a chegada do socorro m\u00e9dico e da Pol\u00edcia Rodovi\u00e1ria Federal (PRF), que assumiram a gest\u00e3o da ocorr\u00eancia de acidente com les\u00f5es corporais.<\/p>\n<p>A atua\u00e7\u00e3o dos servidores, a qual ganhou destaque na imprensa na \u00e9poca do ocorrido, recebeu o texto da mo\u00e7\u00e3o honrosa formalizada pela C\u00e2mara de Vereadores de Mafra, reiterando o nome do CASE Regional de Joinville os cumprimentos pela positiva atitude e comprometimento no socorro \u00e0 v\u00edtima do acidente de tr\u00e2nsito, bem como pela excel\u00eancia nos servi\u00e7os prestados diuturnamente a esta unidade socioeducativa.<\/p>","protected":false},"excerpt":{"rendered":"<p>Recentemente, os agentes de seguran\u00e7a socioeducativos Marcelo Zaranski e Emanuel de Barros, lotados no CASE Regional de Joinville, foram homenageados pela C\u00e2mara de Vereadores de Mafra devido \u00e0 sua destacada atua\u00e7\u00e3o em um atendimento de emerg\u00eancia ocorrido em 3 de outubro na BR 101, pr\u00f3ximo a Itaja\u00ed, envolvendo uma v\u00edtima de acidente de tr\u00e2nsito. No [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":15782,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79,46],"tags":[1336],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 01:05:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/15781"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=15781"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/15781\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/15782"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=15781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=15781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=15781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}