{"id":1610,"date":"2021-02-25T23:30:19","date_gmt":"2021-02-25T23:30:19","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2021\/02\/25\/operacao-maserati-une-as-forcas-de-seguranca-do-estado-para-desarticular-faccao-criminosa-em-santa-catarina\/"},"modified":"2021-02-25T23:30:19","modified_gmt":"2021-02-25T23:30:19","slug":"operacao-maserati-une-as-forcas-de-seguranca-do-estado-para-desarticular-faccao-criminosa-em-santa-catarina","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/operacao-maserati-une-as-forcas-de-seguranca-do-estado-para-desarticular-faccao-criminosa-em-santa-catarina\/","title":{"rendered":"Opera\u00e7\u00e3o Maserati une as for\u00e7as de seguran\u00e7a do estado para desarticular fac\u00e7\u00e3o criminosa em Santa Catarina"},"content":{"rendered":"<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>O Grupo de Atua\u00e7\u00e3o Especial de Combate \u00e0s Organiza\u00e7\u00f5es Criminosas (GAECO), em conjunto com as for\u00e7as de seguran\u00e7a estaduais e federal (Pol\u00edcia Civil, Pol\u00edcia Militar, Pol\u00edcia Rodovi\u00e1ria Federal, Instituto Geral de Per\u00edcia e Pol\u00edcia Penal da Secretaria de Administra\u00e7\u00e3o Prisional e Socioeducativa) de seis estados deflagraram a megaopera\u00e7\u00e3o Maserati nesta quinta-feira (25\/02), contra fac\u00e7\u00e3o criminosa.<\/p>\n<p>Foram cumpridos 120 mandados de pris\u00e3o e 142 de busca e apreens\u00e3o em 45 cidades e em seis Estados da Federa\u00e7\u00e3o &#8211; S\u00e3o Paulo, Paran\u00e1, Mato Grosso do Sul, Minas Gerais, Rio Grande do Sul e Santa Catarina. Participaram da megaopera\u00e7\u00e3o mais de 600 Policiais &#8211; Civis, Militares e Rodovi\u00e1rios Federais -, servidores do Instituto Geral de Per\u00edcias e Policiais Penais do Departamento de Administra\u00e7\u00e3o Prisional. O GAECO identificou que a fac\u00e7\u00e3o criminosa tinha como objetivo primordial a expans\u00e3o da atua\u00e7\u00e3o no Estado de Santa Catarina, com foco na regi\u00e3o de fronteira entre as cidades de S\u00e3o Miguel do Oeste, Chapec\u00f3 e Dion\u00edsio Cerqueira. Assim como na regi\u00e3o de Joinville em raz\u00e3o da proximidade dos Portos de Santa Catarina e Paran\u00e1.<\/p>\n<p>No Curso da Investiga\u00e7\u00e3o foram presas em flagrante 24 pessoas e foram apreendidos 706 kg de subst\u00e2ncias entorpecentes, quatro ve\u00edculos e tr\u00eas armas de fogo.<\/p>\n<p>A Opera\u00e7\u00e3o foi batizada de Maserati em alus\u00e3o ao nome escolhido pela fac\u00e7\u00e3o para identificar o Estado de Santa Catarina. A fac\u00e7\u00e3o criminosa dava nomes de carros aos estados.<\/p>\n<p>Em coletiva na tarde desta quinta-feira (25\/2), foi detalhada a participa\u00e7\u00e3o de cada uma das institui\u00e7\u00f5es na megaopera\u00e7\u00e3o e como a fac\u00e7\u00e3o criminosa atuava.<\/p>\n<p>Atua\u00e7\u00e3o conjunta entre as for\u00e7as de seguran\u00e7a que traz resultados para a sociedade<\/p>\n<p>Os representantes dos \u00f3rg\u00e3os de seguran\u00e7a foram un\u00e2nimes em destacar a atua\u00e7\u00e3o conjunta dos \u00f3rg\u00e3os de seguran\u00e7a, o que faz de Santa Catarina um modelo para os outros estados da federa\u00e7\u00e3o, como destacou o Procurador-Geral de Justi\u00e7a, Fernando da Silva Comin durante a coletiva. &#8220;A opera\u00e7\u00e3o Maserati demonstra que atua\u00e7\u00e3o conjunta dos \u00f3rg\u00e3os de seguran\u00e7a \u00e9 uma realidade e o \u00fanico caminho para combater \u00e0 criminalidade&#8221;, afirmou o PGJ. Comin tamb\u00e9m destacou o trabalho dos GAECOs no Brasil. Somente no ano passado, os GAECOs de 14 Estados, mais o Distrito Federal, deflagraram mais de 40 opera\u00e7\u00f5es de combate a fac\u00e7\u00f5es criminosas, que resultaram em mais de 1 mil pris\u00f5es. Em Santa Catarina, nos \u00faltimos dois anos o GAECO instaurou cerca de 400 procedimentos investigat\u00f3rios contra organiza\u00e7\u00f5es criminosas. E foram efetivadas nesse per\u00edodo em nosso Estado mais de cem pris\u00f5es e cumpridos mais de 600 mandados de busca e apreens\u00e3o.<\/p>\n<p>A coopera\u00e7\u00e3o institucional tamb\u00e9m foi o tom da fala do Subprocurador-Geral de Justi\u00e7a para Assuntos Jur\u00eddicos do MPSC e Coordenador-geral do GAECO de Santa Catarina, Procurador de Justi\u00e7a F\u00e1bio de Souza Trajano: &#8220;O modelo que n\u00f3s temos em Santa Catarina \u00e9 diferenciado em rela\u00e7\u00e3o a outros modelos da federa\u00e7\u00e3o, pois temos sete unidades mais uma coordena\u00e7\u00e3o estadual, e esse modelo \u00e9 fundamental e indispens\u00e1vel para alcan\u00e7armos resultados como hoje, para combater fac\u00e7\u00f5es criminosas, a criminalidade, e crimes contra a administra\u00e7\u00e3o, como a corrup\u00e7\u00e3o.&#8221; ressalta Trajano.<\/p>\n<p>Para o Presidente do Colegiado Superior de Seguran\u00e7a P\u00fablica de Santa Catarina, o Comandante-Geral do Corpo de Bombeiros Militar de Santa Catarina, Charles Alexandre Vieira, &#8220;o sucesso da opera\u00e7\u00e3o \u00e9 gra\u00e7as a uni\u00e3o de esfor\u00e7os de todos os \u00f3rg\u00e3os que trabalharam de forma organizada. Com atua\u00e7\u00f5es como essa, fac\u00e7\u00f5es n\u00e3o ganham espa\u00e7o em Santa Catarina.&#8221;<\/p>\n<p>O Secret\u00e1rio de Administra\u00e7\u00e3o Prisional e Socioeducativa, Leandro Lima, refor\u00e7ou que durante a opera\u00e7\u00e3o no Complexo Penitenci\u00e1rio de Chapec\u00f3 foram observadas todas as medidas sanit\u00e1rias mantendo a seguran\u00e7a de todos os envolvidos, tanto equipe quanto dos internos.<\/p>\n<p>J\u00e1 a Pol\u00edcia Civil atuou com 191 policiais e mais equipe de apoio. O Delegado-Geral da Pol\u00edcia Civil, Paulo Koerich, tamb\u00e9m ressaltou o exemplo de Santa Catarina no enfrentamento ao crime organizado: &#8220;Mais uma vez Santa Catarina d\u00e1 exemplo para o Brasil que \u00e9 poss\u00edvel fazer o dever de casa. Vamos continuar defendendo a sociedade catarinense e fazer valer a lei.&#8221;<\/p>\n<p>O Subcomandante da Pol\u00edcia Militar, Coronel Pontes, disse que o Estado vem diminuindo os \u00edndices de criminalidade e que opera\u00e7\u00f5es como a Maserati &#8220;serve para amenizar o impacto de crimes violentos&#8221;.<\/p>\n<p>A participa\u00e7\u00e3o da Pol\u00edcia Rodovi\u00e1ria Federal foi ressaltada pelo Superintendente da PRF em Santa Catarina, Jean Coelho: &#8220;N\u00f3s estamos comprometidos em eliminar essa cadeia log\u00edstica que est\u00e1 querendo se aproveitar da sociedade e n\u00f3s n\u00e3o vamos permitir que isso aconte\u00e7a, sempre trabalhando juntos com os outros \u00f3rg\u00e3os presentes aqui&#8221;.<\/p>\n<p>O Diretor do IGP, Geovani Adriano, evidenciou o tamanho da opera\u00e7\u00e3o: &#8220;Esse \u00e9 o tipo de crime que n\u00e3o podemos permitir que se perpetue no estado de Santa Catarina. Pela primeira vez em Santa Catarina montamos um laborat\u00f3rio fora de uma unidade nossa. Os profissionais que atuaram em S\u00e3o Miguel do Oeste ficam at\u00e9 terminar os laudos para preservar as provas. Tamb\u00e9m atuaram v\u00e1rios profissionais em Joinville, Ca\u00e7ador e Florian\u00f3polis.&#8221;<\/p>\n<p>Modus Operandi: expandir pelo interior at\u00e9 chegar ao litoral<\/p>\n<p>A investiga\u00e7\u00e3o, conduzida pelo GAECO, teve dura\u00e7\u00e3o de nove meses e revelou que a inten\u00e7\u00e3o da fac\u00e7\u00e3o era expandir a sua atua\u00e7\u00e3o em Santa Catarina, tomar as cidades menores at\u00e9 chegar ao litoral para assim dominar o Estado. Os focos iniciais de expans\u00e3o do grupo seriam S\u00e3o Miguel do Oeste, Chapec\u00f3 e Dion\u00edsio Cerqueira. &#8220;O objetivo da fac\u00e7\u00e3o era expandir a sua atua\u00e7\u00e3o em Santa Catarina e come\u00e7ar essa expans\u00e3o nas cidades menores at\u00e9 chegar no litoral. O foco estava nas cidades do extremo oeste pela proximidade com o Paraguai e Argentina e em Joinville por conta da proximidade com os portos de Santa Catarina, Paran\u00e1 e com a capital Florian\u00f3polis&#8221;, afirmou a Coordenadora do N\u00facleo do GAECO S\u00e3o Miguel do Oeste, Promotora de Justi\u00e7a Marcela de Jesus Boldori Fernandes.<\/p>\n<p>Segundo a investiga\u00e7\u00e3o, para gerir toda essa atividade criminosa, foram criados cargos e fun\u00e7\u00f5es, tal qual uma empresa. Foram identificados 18 cargos, como, por exemplo, um espec\u00edfico para cadastros de potenciais faccionados, outro para gerir a venda de drogas e um para tratar de assuntos que envolviam todo o sistema prisional, entre outros. &#8220;Na investiga\u00e7\u00e3o, verificamos que em outros estados, onde a fac\u00e7\u00e3o j\u00e1 atua h\u00e1 algum tempo, existem mais cargos. Aqui em Santa Catarina a estrutura ainda estava enxuta e ia crescendo conforme evolu\u00edam os batismos&#8221;, afirmou o Integrante do n\u00facleo GAECO S\u00e3o Miguel do Oeste, Delegado Eduardo Mattos.<\/p>\n<p>No decorrer da investiga\u00e7\u00e3o foram identificados e presos faccionados espalhados em diversas cidades dos estados da federa\u00e7\u00e3o, mas que atuavam em Santa Catarina. Al\u00e9m da identifica\u00e7\u00e3o dos faccionados, foram apurados onze homic\u00eddios, quatro tentativas de homic\u00eddio e diversos roubos.<\/p>\n<p>Pr\u00f3ximos passos<\/p>\n<p>O Promotor de Justi\u00e7a com atua\u00e7\u00e3o na \u00e1rea criminal em S\u00e3o Miguel do Oeste, Marciano Villa, esclareceu, durante a coletiva de imprensa, os pr\u00f3ximos passos da investiga\u00e7\u00e3o: &#8220;Assim que houver a conclus\u00e3o do inqu\u00e9rito pelo GAECO, teremos os prazos legais, para que junto com os demais Promotores de Justi\u00e7a, analisarmos todos os fatos para fazer o enquadramento legal dos crimes cometidos pela fac\u00e7\u00e3o e ter uma solu\u00e7\u00e3o eficiente e c\u00e9lere e dar a resposta que a sociedade catarinense espera&#8221;, finalizou.<\/p>\n<p>Fonte: Coordenadoria de Comunica\u00e7\u00e3o Social do MPSC<\/p>","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; &nbsp; &nbsp; O Grupo de Atua\u00e7\u00e3o Especial de Combate \u00e0s Organiza\u00e7\u00f5es Criminosas (GAECO), em conjunto com as for\u00e7as de seguran\u00e7a estaduais e federal (Pol\u00edcia Civil, Pol\u00edcia Militar, Pol\u00edcia Rodovi\u00e1ria Federal, Instituto Geral de Per\u00edcia e Pol\u00edcia Penal da Secretaria de Administra\u00e7\u00e3o Prisional e Socioeducativa) de seis estados deflagraram a megaopera\u00e7\u00e3o Maserati nesta quinta-feira [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":1609,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:12:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1610"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=1610"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/1610\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=1610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=1610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=1610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}