{"id":19621,"date":"2024-07-15T19:02:29","date_gmt":"2024-07-15T22:02:29","guid":{"rendered":"https:\/\/www.sap.sc.gov.br\/?p=19621"},"modified":"2024-07-15T19:02:29","modified_gmt":"2024-07-15T22:02:29","slug":"centro-de-treinamento-de-jiu-jitsu-da-policia-penal-de-sc","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/centro-de-treinamento-de-jiu-jitsu-da-policia-penal-de-sc\/","title":{"rendered":"CENTRO DE TREINAMENTO DE JIU-JITSU DA POL\u00cdCIA PENAL DE SC"},"content":{"rendered":"<p>\u00c9 com grande orgulho que anunciamos a inaugura\u00e7\u00e3o do nosso novo centro de treinamento, equipe de Jiu-Jitsu Brasileiro, localizado na Academia de Administra\u00e7\u00e3o Prisional e Socioeducativa da SAP\/SC!<\/p>\n<p>Nosso tatame est\u00e1 oficialmente credenciado pela IBJJF (International Brazilian Jiu-Jitsu Federation) e pela CBJJ (Confedera\u00e7\u00e3o Brasileira de Jiu-Jitsu), permitindo a diploma\u00e7\u00e3o de gradua\u00e7\u00e3o.<\/p>\n<p>E o melhor de tudo: as aulas ser\u00e3o sem custos para os servidores da SAP\/SC! As sess\u00f5es ocorrer\u00e3o todas as segundas e quartas-feiras, a partir das 19h30min.<\/p>\n<p>Venha treinar com a gente e aperfei\u00e7oar suas habilidades! Este \u00e9 mais um passo na nossa miss\u00e3o de promover a sa\u00fade, a disciplina e a excel\u00eancia entre nossos servidores. N\u00e3o perca essa oportunidade \u00fanica!<\/p>\n<p>Aulas: Segundas e Quartas-feiras<br \/>\nHor\u00e1rio: 19h30min<br \/>\nLocal: Academia de Administra\u00e7\u00e3o Prisional e Socioeducativa da SAP\/SC<\/p>\n<p>ATEN\u00c7\u00c3O INTERESSADOS<\/p>\n<p>Favor preencher a ficha de inscri\u00e7\u00e3o para participar: <a href=\"https:\/\/forms.gle\/9pdtKXCikeTMm3yK7\">https:\/\/forms.gle\/9pdtKXCikeTMm3yK7<\/a><\/p>\n<p>Em breve ser\u00e1 divulgada a data de in\u00edcio!<\/p>\n<p>Vamos juntos fortalecer nosso corpo e mente!<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00c9 com grande orgulho que anunciamos a inaugura\u00e7\u00e3o do nosso novo centro de treinamento, equipe de Jiu-Jitsu Brasileiro, localizado na Academia de Administra\u00e7\u00e3o Prisional e Socioeducativa da SAP\/SC! Nosso tatame est\u00e1 oficialmente credenciado pela IBJJF (International Brazilian Jiu-Jitsu Federation) e pela CBJJ (Confedera\u00e7\u00e3o Brasileira de Jiu-Jitsu), permitindo a diploma\u00e7\u00e3o de gradua\u00e7\u00e3o. E o melhor de [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":19622,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1322,1315],"tags":[1336],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 01:05:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/19621"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=19621"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/19621\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/19622"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=19621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=19621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=19621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}