{"id":2119,"date":"2020-12-10T16:05:45","date_gmt":"2020-12-10T19:05:45","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/dispensa-de-chamamento-publico-n-002-sap-2020-deap\/"},"modified":"2024-01-02T15:35:31","modified_gmt":"2024-01-02T18:35:31","slug":"dispensa-de-chamamento-publico-n-002-sap-2020-deap","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/dispensa-de-chamamento-publico-n-002-sap-2020-deap\/","title":{"rendered":"DISPENSA DE CHAMAMENTO P\u00daBLICO N\u00ba 002\/SAP\/2020\/DEAP"},"content":{"rendered":"<div style=\"text-align: justify;\">A Secretaria de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa, considerando a necessidade de perman\u00eancia da operacionaliza\u00e7\u00e3o das centrais de penas e medidas alternativas, pelo per\u00edodo necess\u00e1rio \u00e0 conclus\u00e3o do Processo Seletivo para a contrata\u00e7\u00e3o de profissionais que atuar\u00e3o nas equipes de cada CPMA. Com base na excepcionalidade prevista no art. 8\u00ba, \u00a7 2\u00ba do Decreto Estadual n\u00ba 1196, de 21 de julho de 2017, torna p\u00fablico o extrato da justificativa de dispensa de chamamento p\u00fabliconos termos do art. 32 da Lei 13.019\/2014.<\/div>\n<ul>\n<li><a href=\"https:\/\/sap.sc.gov.br\/en\/download\/01_extrato-de-publicacao-da-dispensa-de-chamamento-cpma-pdf\/\" target=\"_blank\" rel=\"noopener\">Extrato<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa, considerando a necessidade de perman\u00eancia da operacionaliza\u00e7\u00e3o das centrais de penas e medidas alternativas, pelo per\u00edodo necess\u00e1rio \u00e0 conclus\u00e3o do Processo Seletivo para a contrata\u00e7\u00e3o de profissionais que atuar\u00e3o nas equipes de cada CPMA. Com base na excepcionalidade prevista no art. 8\u00ba, \u00a7 2\u00ba do Decreto [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[67],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 00:19:47","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2119"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2119"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2119\/revisions"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2119"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2119"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}