{"id":2142,"date":"2021-04-08T19:07:00","date_gmt":"2021-04-08T22:07:00","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/edital-n-003-2021-acaps-sap-processo-de-credenciamento-e-selecao-de-servidor-docente\/"},"modified":"2025-01-28T10:07:28","modified_gmt":"2025-01-28T13:07:28","slug":"edital-n-003-2021-acaps-sap-processo-de-credenciamento-e-selecao-de-servidor-docente","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/edital-n-003-2021-acaps-sap-processo-de-credenciamento-e-selecao-de-servidor-docente\/","title":{"rendered":"EDITAL N.\u00ba 003\/2021\/ACAPS\/SAP &#8211; PROCESSO DE CREDENCIAMENTO E SELE\u00c7\u00c3O DE SERVIDOR DOCENTE"},"content":{"rendered":"<div style=\"text-align: justify;\">O SECRET\u00c1RIO DE ESTADO DA ADMINISTRA\u00c7\u00c3O PRISIONAL E SOCIOEDUCATIVA, O DIRETOR DA ACADEMIA DE ADMINISTRA\u00c7\u00c3O PRISIONAL E SOCIOEDUCATIVA E A COMISS\u00c3O DE CREDENCIAMENTO E SELE\u00c7\u00c3O, nomeada pela Portaria n\u00ba016\/ACAPS\/GABS\/SAP e altera\u00e7\u00f5es, em conformidade com o art. 6\u00ba do Decreto n.\u00ba 802, de 09 de fevereiro de 2012, faz saber, a quem interessar possa, que est\u00e3o abertas as inscri\u00e7\u00f5es para o Processo de Credenciamento e Sele\u00e7\u00e3o de Servidor Docente para atua\u00e7\u00e3o na Academia de Administra\u00e7\u00e3o Prisional e Socioeducativa \u2013 Acaps, que se reger\u00e1 pelas normas estabelecidas neste edital, pelo regimento interno da Acaps e pela legisla\u00e7\u00e3o vigente.<\/div>\n<ul>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/index.php\/consultas\/downloads\/credenciamento\/credenciamento-2021\/edital-n-003-2021-acaps-sap-docentes\/1664-1-edital-docentes-inteligencia-2021\/file\" target=\"_blank\" rel=\"noopener\">Edital<br \/>\n<\/a><\/li>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/index.php\/consultas\/downloads\/credenciamento\/credenciamento-2021\/edital-n-003-2021-acaps-sap-docentes\/1665-2-ficha-de-inscricao-credenciamento-docentes-1\/file\" target=\"_blank\" rel=\"noopener\">Ficha de Inscri\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/index.php\/consultas\/downloads\/credenciamento\/credenciamento-2021\/edital-n-003-2021-acaps-sap-docentes\/1666-3-formulario-de-recurso\/file\" target=\"_blank\" rel=\"noopener\">Formul\u00e1rio de Recurso<\/a><\/li>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/index.php\/consultas\/downloads\/credenciamento\/credenciamento-2021\/edital-n-003-2021-acaps-sap-docentes\/1698-4-resultado-preliminar-edital-n-003-2021-credenciamento\/file\" target=\"_blank\" rel=\"noopener\">Resultado Preliminar<\/a><\/li>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/index.php\/consultas\/downloads\/credenciamento\/credenciamento-2021\/edital-n-003-2021-acaps-sap-docentes\/1706-5-retificacao-de-datas\/file\" target=\"_blank\" rel=\"noopener\">Retifica\u00e7\u00e3o de Datas<\/a><\/li>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/index.php\/consultas\/downloads\/credenciamento\/credenciamento-2021\/edital-n-003-2021-acaps-sap-docentes\/1707-6-resultado-final\/file\" target=\"_blank\" rel=\"noopener\">Resultado Final<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>O SECRET\u00c1RIO DE ESTADO DA ADMINISTRA\u00c7\u00c3O PRISIONAL E SOCIOEDUCATIVA, O DIRETOR DA ACADEMIA DE ADMINISTRA\u00c7\u00c3O PRISIONAL E SOCIOEDUCATIVA E A COMISS\u00c3O DE CREDENCIAMENTO E SELE\u00c7\u00c3O, nomeada pela Portaria n\u00ba016\/ACAPS\/GABS\/SAP e altera\u00e7\u00f5es, em conformidade com o art. 6\u00ba do Decreto n.\u00ba 802, de 09 de fevereiro de 2012, faz saber, a quem interessar possa, que est\u00e3o [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[42],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 22:09:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2142"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2142"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2142\/revisions"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2142"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2142"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2142"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}