{"id":2150,"date":"2021-06-08T17:55:23","date_gmt":"2021-06-08T20:55:23","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/dispensa-de-chamamento-publico-n-001-sap-2021-deap\/"},"modified":"2021-06-08T17:55:23","modified_gmt":"2021-06-08T20:55:23","slug":"dispensa-de-chamamento-publico-n-001-sap-2021-deap","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/dispensa-de-chamamento-publico-n-001-sap-2021-deap\/","title":{"rendered":"DISPENSA DE CHAMAMENTO P\u00daBLICO N\u00ba 001\/SAP\/2021\/DEAP"},"content":{"rendered":"<div style=\"text-align: justify;\">A Secretaria de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa, por for\u00e7a de disposi\u00e7\u00e3o contratual (contrato n\u00ba 134\/2020\/SAP) utilizar\u00e1 a m\u00e3o de obra dos reeducandos do sistema prisional para realizar a conversa\u00e7\u00e3o, manuten\u00e7\u00e3o geral, cozinha e demais atividades essenciais ao funcionamento do Complexo Penitenci\u00e1rio do Vale do Itaja\u00ed. Com base na excepcionalidade prevista no\u00a7 2\u00ba do art. 8\u00ba do Decreto Estadual n\u00ba 1.196\/2017, torna p\u00fablico o extrato da justificativa de Dispensa de Chamamento P\u00fablico nos termos do art. 32 da Lei Federal 13.019\/2014, conforme previsto no Processo n\u00ba SAP 66710\/2020, que visa \u00e0 formaliza\u00e7\u00e3o de Termo de Parceria Laboral com a empresa Solu\u00e7\u00f5es Servi\u00e7os Terceirizados Eireli, para atender o m\u00ednimo de 34 (trinta e quatro) reeducandos no Complexo Penitenci\u00e1rio do Vale do Itaja\u00ed \u2013 CPVI. A vig\u00eancia ser\u00e1 do in\u00edcio do contrato n\u00ba 134\/2020\/SAP (PE 0056\/2019\/SEA \u2013 SJC 61684\/2018) at\u00e9 a data do seu encerramento.<\/div>\n<ul>\n<li><a href=\"https:\/\/sap.sc.gov.br\/index.php\/consultas\/downloads\/chamamento-publico\/chamamento-2021\/dispensa-de-chamamento-n-001-2021-sap-deap\/1728-extrato-dispensa-001-2021\/file\" target=\"_blank\" rel=\"noopener\">Extrato<br \/><\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa, por for\u00e7a de disposi\u00e7\u00e3o contratual (contrato n\u00ba 134\/2020\/SAP) utilizar\u00e1 a m\u00e3o de obra dos reeducandos do sistema prisional para realizar a conversa\u00e7\u00e3o, manuten\u00e7\u00e3o geral, cozinha e demais atividades essenciais ao funcionamento do Complexo Penitenci\u00e1rio do Vale do Itaja\u00ed. Com base na excepcionalidade prevista no\u00a7 2\u00ba do [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[67],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 01:02:22","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2150"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2150"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2150\/revisions"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}