{"id":2158,"date":"2021-08-31T16:59:34","date_gmt":"2021-08-31T19:59:34","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/edital-de-credenciamento-n-001-2021-sap-gepae\/"},"modified":"2025-01-28T09:57:37","modified_gmt":"2025-01-28T12:57:37","slug":"edital-de-credenciamento-n-001-2021-sap-gepae","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/edital-de-credenciamento-n-001-2021-sap-gepae\/","title":{"rendered":"EDITAL DE CREDENCIAMENTO N\u00ba 001\/2021\/SAP\/GEPAE"},"content":{"rendered":"<div style=\"text-align: justify;\">O ESTADO DE SANTA CATARINA, por meio da SECRETARIA DE ESTADO DA ADMINISTRA\u00c7\u00c3O PRISIONAL E SOCIOEDUCATIVA \u2013SAP, doravante denominada PARCEIRA P\u00daBLICA, torna p\u00fablico o presente EDITAL DE CREDENCIAMENTO para sele\u00e7\u00e3o de Institui\u00e7\u00f5es Privadas sem Fins Lucrativos para cria\u00e7\u00e3o de vagas para o cumprimento, acompanhamento das penas e medidas alternativas e acesso a direitos \u00e0s pessoas em alternativas penais, para execu\u00e7\u00e3o em todo o Estado de Santa Catarina, conforme base legal: Leis Federais n. 7.210\/1984 \u2013Lei de Execu\u00e7\u00e3o Penal; n. 9.714\/1988 \u2013Altera o C\u00f3digo Penal; n. 9.099\/1995 \u2013Disp\u00f5e sobre os Juizados Especiais C\u00edveis e Criminais; n. 10.259\/2001 \u2013Disp\u00f5e sobre a institui\u00e7\u00e3o dos Juizados C\u00edveis e Especiais no \u00e2mbito da Justi\u00e7a Federal; n. 10.826\/2003 \u2013Disp\u00f5e sobe o Sistema Nacional de Armas SINARM; n. 11.343\/2006 \u2013Institui o Sistema Nacional de Pol\u00edticas P\u00fablicas sobre Drogas \u2013SISNAD; n. 13,019\/2014 estabelece o regime jur\u00eddico das parcerias entre a administra\u00e7\u00e3o p\u00fablica e as organiza\u00e7\u00f5es da sociedade civil; Lei 8.666\/1993 que estabelece normas de licita\u00e7\u00f5es e contratos, neste caso, especialmente, seu art. 116; Constitui\u00e7\u00e3o Federal de 1988; Resolu\u00e7\u00e3o do Conselho Nacional de Pol\u00edtica Criminal e Penitenci\u00e1ria; Programa Nacional de Direitos Humanos (Dec. 7.037\/09); Plano Nacional de Pol\u00edtica Criminal e Penitenci\u00e1ria, Manual de Gest\u00e3o para Alternativas Penais e o Decreto Estadual n. 1.012\/2012 que cria o Programa Central de Penas e Medidas Alternativas do Estado.<\/div>\n<ul>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/index.php\/consultas\/downloads\/credenciamento\/credenciamento-2021\/edital-n-001-2021-gecap-sap-cpma\/1807-01-edital-de-credenciamento-001-21\/file\" target=\"_blank\" rel=\"noopener\">Edital<\/a><\/li>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/index.php\/consultas\/downloads\/credenciamento\/credenciamento-2021\/edital-n-001-2021-gecap-sap-cpma\/1808-02-formulario-de-cadastro\/file\" target=\"_blank\" rel=\"noopener\">Formul\u00e1rio de Cadastro<\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">IMPRESCIND\u00cdVEL: preenchimento do Formul\u00e1rio de Cadastro devidamente assinado e identificado, para o e-mail da comarca de interesse, encaminhado juntamente com a documenta\u00e7\u00e3o solicitada conforme termos do edital.<\/p>\n<p>In\u00edcio das propostas: 31\/08\/2021<br \/>\nPrazo de encerramento: 31\/12\/2022<\/p>\n<p style=\"text-align: justify;\">As d\u00favidas poder\u00e3o ser encaminhadas pelo e-mail: <a href=\"mailto:gefun@sejuri.sc.gov.br\">gefun@sejuri.sc.gov.br<\/a> ou pelo telefone (48) 3664-5814.<\/p>","protected":false},"excerpt":{"rendered":"<p>O ESTADO DE SANTA CATARINA, por meio da SECRETARIA DE ESTADO DA ADMINISTRA\u00c7\u00c3O PRISIONAL E SOCIOEDUCATIVA \u2013SAP, doravante denominada PARCEIRA P\u00daBLICA, torna p\u00fablico o presente EDITAL DE CREDENCIAMENTO para sele\u00e7\u00e3o de Institui\u00e7\u00f5es Privadas sem Fins Lucrativos para cria\u00e7\u00e3o de vagas para o cumprimento, acompanhamento das penas e medidas alternativas e acesso a direitos \u00e0s pessoas [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[42],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 22:09:02","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2158"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2158"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2158\/revisions"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}