{"id":21613,"date":"2025-07-22T14:24:47","date_gmt":"2025-07-22T17:24:47","guid":{"rendered":"https:\/\/sejuri.sc.gov.br\/?p=21613"},"modified":"2025-07-22T14:24:47","modified_gmt":"2025-07-22T17:24:47","slug":"dispensa-de-chamamento-publico-emergencial-parceria-laboral-n-014-2025-sejuri-gefun","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/dispensa-de-chamamento-publico-emergencial-parceria-laboral-n-014-2025-sejuri-gefun\/","title":{"rendered":"DISPENSA DE CHAMAMENTO P\u00daBLICO &#8211; EMERG\u00caNCIAL &#8211; PARCERIA LABORAL N. 014\/2025\/SEJURI\/GEFUN"},"content":{"rendered":"<p>Com base na excepcionalidade prevista no inciso I do art. 30 e na forma do art 32, ambos da Lei 13019\/2014, a qual se aplica subsidiariamente, quanto aos procedimentos, ao chamamento p\u00fablico para celebra\u00e7\u00e3o de parceria laboral previstas no art. 23 da Lei Complementar 809\/2022, torna p\u00fablico o extrato da justificativa de Dispensa de Chamamento P\u00fablico (SAP 00124920\/2024), a qual visa \u00e0 formaliza\u00e7\u00e3o de Parceria Laboral com a oferta de 30 vagas de trabalho aos presos do Pres\u00eddio Masculino de Itajai, com cess\u00e3o do espa\u00e7o medindo 182m\u00b2 pelo prazo de at\u00e9 180 dias ou at\u00e9 que se conclua o processo de chamamento p\u00fablico, o que ocorrer primeiro, com a empresa IND. TEXTIL PORTO FRANCO LTDA.<\/p>\n<p>Fica concedido o prazo de 5 dias para impugna\u00e7\u00e3o (Lei 13.019\/2014)<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/01_processo-sap-00124920_2024\/\" target=\"_blank\" rel=\"noopener\">Extrato<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Com base na excepcionalidade prevista no inciso I do art. 30 e na forma do art 32, ambos da Lei 13019\/2014, a qual se aplica subsidiariamente, quanto aos procedimentos, ao chamamento p\u00fablico para celebra\u00e7\u00e3o de parceria laboral previstas no art. 23 da Lei Complementar 809\/2022, torna p\u00fablico o extrato da justificativa de Dispensa de Chamamento [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[67],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 22:56:28","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/21613"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=21613"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/21613\/revisions"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=21613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=21613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=21613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}