{"id":22262,"date":"2025-09-05T18:35:45","date_gmt":"2025-09-05T21:35:45","guid":{"rendered":"https:\/\/sejuri.sc.gov.br\/?p=22262"},"modified":"2025-09-05T18:43:51","modified_gmt":"2025-09-05T21:43:51","slug":"dispensa-de-chamamento-publico-emergencial-no-027-2025","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/dispensa-de-chamamento-publico-emergencial-no-027-2025\/","title":{"rendered":"DISPENSA DE CHAMAMENTO P\u00daBLICO N\u00ba 027\/2025"},"content":{"rendered":"<p>A Secretaria de Estado de Justi\u00e7a e Reintegra\u00e7\u00e3o Social resolve, com base na excepcionalidade prevista no art. 20 da Lei Complementar\u00a0809\/2022, tornar p\u00fablico o extrato da justificativa de Dispensa de Chamamento P\u00fablico, a qual visa \u00e0 formaliza\u00e7\u00e3o de Parceria Laboral com a oferta de 70 (setenta) vagas\u00a0 de\u00a0 trabalho\u00a0 EXTERNO\u00a0 aos\u00a0 presos\u00a0 do\u00a0 regime\u00a0 semiaberto\u00a0 da\u00a0 Penitenci\u00e1ria Agr\u00edcola\u00a0 de\u00a0 Chapec\u00f3,\u00a0 pelo\u00a0 prazo\u00a0 de\u00a0 60\u00a0 (sessenta)\u00a0 meses,\u00a0 com\u00a0 as\u00a0 empresas AZEPLAST IND\u00daSTRIA E COMERCIO LTDA e COMPENSADOS BR LTDA.<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/extrato\/\" target=\"_blank\" rel=\"noopener\">Extrato<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado de Justi\u00e7a e Reintegra\u00e7\u00e3o Social resolve, com base na excepcionalidade prevista no art. 20 da Lei Complementar\u00a0809\/2022, tornar p\u00fablico o extrato da justificativa de Dispensa de Chamamento P\u00fablico, a qual visa \u00e0 formaliza\u00e7\u00e3o de Parceria Laboral com a oferta de 70 (setenta) vagas\u00a0 de\u00a0 trabalho\u00a0 EXTERNO\u00a0 aos\u00a0 presos\u00a0 do\u00a0 regime\u00a0 semiaberto\u00a0 [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[67],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 22:55:51","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/22262"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=22262"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/22262\/revisions"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=22262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=22262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=22262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}