{"id":22320,"date":"2025-09-10T16:59:21","date_gmt":"2025-09-10T19:59:21","guid":{"rendered":"https:\/\/www.sap.sc.gov.br\/?p=22320"},"modified":"2025-09-10T16:59:21","modified_gmt":"2025-09-10T19:59:21","slug":"policia-penal-participa-de-reuniao-de-alinhamento-para-a-40a-edicao-da-oktoberfest","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/policia-penal-participa-de-reuniao-de-alinhamento-para-a-40a-edicao-da-oktoberfest\/","title":{"rendered":"Pol\u00edcia Penal participa de reuni\u00e3o de alinhamento para a 40\u00aa edi\u00e7\u00e3o da Oktoberfest"},"content":{"rendered":"<p>Na tarde desta ter\u00e7a-feira, foi realizada a reuni\u00e3o de alinhamento para a 40\u00aa edi\u00e7\u00e3o da Oktoberfest, que acontece entre os dias 8 e 26 de outubro, em Blumenau. O encontro teve como objetivo esclarecer e organizar as demandas necess\u00e1rias para a realiza\u00e7\u00e3o de mais um grande evento, considerado o maior da cultura germ\u00e2nica das Am\u00e9ricas.<\/p>\n<p>A Pol\u00edcia Penal de Santa Catarina j\u00e1 marcou presen\u00e7a em edi\u00e7\u00f5es anteriores da Oktoberfest e, neste ano, ter\u00e1 novamente participa\u00e7\u00e3o oficial na seguran\u00e7a da festa. Ao todo, 10 policiais penais atuar\u00e3o diariamente, entre equipes da Unidade de Monitoramento Eletr\u00f4nico (UME), do N\u00facleo de Recapturas (RECAP) e do N\u00facleo de Opera\u00e7\u00f5es T\u00e1ticas (NOT 07).<\/p>\n<p><a href=\"http:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-10-at-15.09.09.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-large wp-image-22322\" src=\"http:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-10-at-15.09.09-1024x576.jpeg\" alt=\"\" width=\"696\" height=\"392\" srcset=\"https:\/\/sap.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-10-at-15.09.09-1024x576.jpeg 1024w, https:\/\/sap.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-10-at-15.09.09-300x169.jpeg 300w, https:\/\/sap.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-10-at-15.09.09-768x432.jpeg 768w, https:\/\/sap.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-10-at-15.09.09.jpeg 1280w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/a><\/p>\n<p>Uma das novidades ser\u00e1 a alimenta\u00e7\u00e3o do sistema de reconhecimento facial do evento com os dados dos monitorados pela institui\u00e7\u00e3o. Com isso, ser\u00e1 poss\u00edvel identificar, por meio das c\u00e2meras instaladas no parque, aqueles que eventualmente estiverem descumprindo as regras no monitoramento eletr\u00f4nico ou sejam considerados foragidos do sistema penitenci\u00e1rio.<\/p>\n<p>A Pol\u00edcia Penal tamb\u00e9m contar\u00e1, pela primeira vez, com uma base operacional pr\u00f3pria dentro da Oktoberfest, al\u00e9m de espa\u00e7o espec\u00edfico para as viaturas. Um policial penal estar\u00e1 presente no Centro de Comando e Monitoramento da festa, garantindo mais agilidade no repasse de informa\u00e7\u00f5es \u00e0s equipes que atuam no entorno do evento. O objetivo \u00e9 facilitar a abordagem ou recaptura quando necess\u00e1rio, refor\u00e7ando a integra\u00e7\u00e3o entre os \u00f3rg\u00e3os de seguran\u00e7a.<\/p>\n<p>A presen\u00e7a da Pol\u00edcia Penal na Oktoberfest representa um passo importante na consolida\u00e7\u00e3o da institui\u00e7\u00e3o como parte efetiva do sistema de seguran\u00e7a em grandes eventos de Santa Catarina, ampliando a prote\u00e7\u00e3o tanto para os participantes quanto para a popula\u00e7\u00e3o em geral.<\/p>\n<p><a href=\"http:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-10-at-13.53.46.jpeg\"><img decoding=\"async\" class=\"aligncenter size-large wp-image-22323\" src=\"http:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-10-at-13.53.46-1024x768.jpeg\" alt=\"\" width=\"696\" height=\"522\" srcset=\"https:\/\/sap.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-10-at-13.53.46-1024x768.jpeg 1024w, https:\/\/sap.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-10-at-13.53.46-300x225.jpeg 300w, https:\/\/sap.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-10-at-13.53.46-768x576.jpeg 768w, https:\/\/sap.sc.gov.br\/wp-content\/uploads\/2025\/09\/WhatsApp-Image-2025-09-10-at-13.53.46.jpeg 1204w\" sizes=\"(max-width: 696px) 100vw, 696px\" \/><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Na tarde desta ter\u00e7a-feira, foi realizada a reuni\u00e3o de alinhamento para a 40\u00aa edi\u00e7\u00e3o da Oktoberfest, que acontece entre os dias 8 e 26 de outubro, em Blumenau. O encontro teve como objetivo esclarecer e organizar as demandas necess\u00e1rias para a realiza\u00e7\u00e3o de mais um grande evento, considerado o maior da cultura germ\u00e2nica das Am\u00e9ricas. [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":22321,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[46],"tags":[1336],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 00:58:08","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/22320"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=22320"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/22320\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/22321"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=22320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=22320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=22320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}