{"id":2285,"date":"2022-12-23T15:03:08","date_gmt":"2022-12-23T18:03:08","guid":{"rendered":"http:\/\/websap2023.intranet.ciasc.gov.br\/chamamento-n-008-sap-dpp-2022\/"},"modified":"2024-01-03T11:51:16","modified_gmt":"2024-01-03T14:51:16","slug":"chamamento-n-008-sap-dpp-2022","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/chamamento-n-008-sap-dpp-2022\/","title":{"rendered":"CHAMAMENTO N\u00ba 008\/SAP\/DPP\/2022"},"content":{"rendered":"<div style=\"text-align: justify;\">O Estado de Santa Catarina, por meio da Secretaria de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa (SAP), aqui denominado PARCEIRO P\u00daBLICO, torna p\u00fablico o EDITAL DE CHAMAMENTO P\u00daBLICO para celebra\u00e7\u00e3o de instrumentos de parceiros cujo objeto \u00e9 o desenvolvimento de ATIVIDADES LABORAIS EXTERNAS aos reeducandos do sistema prisional do Estado de Santa Catarina, com execu\u00e7\u00e3o pelo FUNDO ROTATIVO NA PENITENCI\u00c1RIA DE FLORIAN\u00d3POLIS e fiscaliza\u00e7\u00e3o pelo DEPARTAMENTO DE POL\u00cdCIA PENAL (DPP) na UNIDADE: PRES\u00cdDIO REGIONAL DE TIJUCAS com aplica\u00e7\u00e3o do disposto na Lei 7.210 de 11 de julho de 1984, na Lei Estadual dos Fundos Rotativos n. 5.455\/1978 e n. 17637\/2018, e nas condi\u00e7\u00f5es estabelecidas neste edital, aplicando no que couber os dispositivos da Lei Federal n\u00b0 8.666\/93.<\/div>\n<p>&nbsp;<\/p>\n<div style=\"text-align: justify;\">IMPRESCIND\u00cdVEL: preenchimento do Formul\u00e1rio da Proposta de Plano de Trabalho e Capacita\u00e7\u00e3o e do Question\u00e1rio de investiga\u00e7\u00e3o Social, devidamente assinados e identificados (identifica\u00e7\u00e3o do respons\u00e1vel pela proponente\/carimbo do CNPJ e envio para o email abaixo: <a href=\"mailto:chamamentopublico@sap.sc.gov.br\">chamamentopublico@sap.sc.gov.br<\/a><\/div>\n<p>In\u00edcio das propostas: 23\/12\/2022.<br \/>\nPrazo de encerramento: 23\/01\/2023.<\/p>\n<p>As d\u00favidas poder\u00e3o ser encaminhadas pelo\u00a0e-mail: <a href=\"mailto:chamamentopublico@sap.sc.gov.br\">chamamentopublico@sap.sc.gov.br<\/a> ou pelo telefone (48) 3664-5814.<\/p>\n<ul>\n<li><a href=\"https:\/\/sap.sc.gov.br\/en\/download\/01_edital-chamamento-008_2022-pdf\/\" target=\"_blank\" rel=\"noopener\">Edital<\/a><\/li>\n<li><a href=\"https:\/\/sap.sc.gov.br\/en\/download\/02_pptc_008_2022-docx\/\" target=\"_blank\" rel=\"noopener\">PPTC<\/a><\/li>\n<li><a href=\"https:\/\/sap.sc.gov.br\/en\/download\/03_qis_008_2022-docx\/\" target=\"_blank\" rel=\"noopener\">QIS<\/a><\/li>\n<li><a href=\"https:\/\/sap.sc.gov.br\/en\/download\/04_edital-chamamento-008_2022_retificado\/\" target=\"_blank\" rel=\"noopener\">Edital Retificado<\/a><\/li>\n<li><a href=\"https:\/\/sap.sc.gov.br\/en\/download\/05_resultado-habilitacao-3\/\" target=\"_blank\" rel=\"noopener\">Resultado Habilita\u00e7\u00e3o<\/a><\/li>\n<li><a href=\"https:\/\/sap.sc.gov.br\/en\/download\/06_segunda-fase-resultado-preliminar-assinado\/\" target=\"_blank\" rel=\"noopener\">Segunda Fase &#8211; Resultado Preliminar<\/a><\/li>\n<li><a href=\"https:\/\/sap.sc.gov.br\/en\/download\/07_segunda-fase-resultado-final\/\" target=\"_blank\" rel=\"noopener\">Segunda Fase &#8211; Resultado Final<\/a><\/li>\n<li><a href=\"https:\/\/sap.sc.gov.br\/en\/download\/08_documento-sap-00008439_2022-1\/\" target=\"_blank\" rel=\"noopener\">Resultado Final Definitivo &#8211; Homologa\u00e7\u00e3o<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>O Estado de Santa Catarina, por meio da Secretaria de Estado da Administra\u00e7\u00e3o Prisional e Socioeducativa (SAP), aqui denominado PARCEIRO P\u00daBLICO, torna p\u00fablico o EDITAL DE CHAMAMENTO P\u00daBLICO para celebra\u00e7\u00e3o de instrumentos de parceiros cujo objeto \u00e9 o desenvolvimento de ATIVIDADES LABORAIS EXTERNAS aos reeducandos do sistema prisional do Estado de Santa Catarina, com execu\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[67],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 22:52:56","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2285"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2285"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2285\/revisions"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}