{"id":23110,"date":"2025-11-11T18:14:56","date_gmt":"2025-11-11T21:14:56","guid":{"rendered":"https:\/\/sejuri.sc.gov.br\/?p=23110"},"modified":"2025-11-17T18:54:23","modified_gmt":"2025-11-17T21:54:23","slug":"inexigibilidade-de-chamamento-publico-01-2025","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/inexigibilidade-de-chamamento-publico-01-2025\/","title":{"rendered":"INEXIGIBILIDADE DE CHAMAMENTO P\u00daBLICO 01\/2025"},"content":{"rendered":"<p><span lang=\"PT\">O presente instrumento tem por objeto a parceria entre a Secretaria de Estado de Justi\u00e7a e Reintegra\u00e7\u00e3o Social (SEJURI) e o Fundo Rotativo Regional da Grande Florian\u00f3polis com a OSC\u00a0<\/span><b><span lang=\"PT\">ASSOCIA\u00c7\u00c3O BENEFICIENTE S\u00c3O DIMAS (ASBEDIM),\u00a0<\/span><\/b><span lang=\"PT\">para a disponibilidade de 09 vagas de trabalho aos presos da Penitenci\u00e1ria de Florian\u00f3polis.<\/span><\/p>\n<p><span lang=\"PT\">Fica concedido o prazo de 5 dias para impugna\u00e7\u00e3o (Lei 13.019\/2014)<br \/>\n<\/span><\/p>\n<ul>\n<li>\n<div><a href=\"https:\/\/sejuri.sc.gov.br\/download\/inexigibilidade-de-chamamento-publico-01-2025\/\">INEXIGIBILIDADE DE CHAMAMENTO P\u00daBLICO 01\/2025<\/a><\/div>\n<div><\/div>\n<\/li>\n<li><a href=\"https:\/\/sejuri.sc.gov.br\/download\/inexigibilidade-de-chamamento-publico-01-2025-retificacao\/\">INEXIGIBILIDADE DE CHAMAMENTO P\u00daBLICO 01\/2025 &#8211; RETIFICA\u00c7\u00c3O<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>O presente instrumento tem por objeto a parceria entre a Secretaria de Estado de Justi\u00e7a e Reintegra\u00e7\u00e3o Social (SEJURI) e o Fundo Rotativo Regional da Grande Florian\u00f3polis com a OSC\u00a0ASSOCIA\u00c7\u00c3O BENEFICIENTE S\u00c3O DIMAS (ASBEDIM),\u00a0para a disponibilidade de 09 vagas de trabalho aos presos da Penitenci\u00e1ria de Florian\u00f3polis. Fica concedido o prazo de 5 dias para [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[67],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 22:54:27","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/23110"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=23110"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/23110\/revisions"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=23110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=23110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=23110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}