{"id":23314,"date":"2025-11-27T15:29:39","date_gmt":"2025-11-27T18:29:39","guid":{"rendered":"https:\/\/sejuri.sc.gov.br\/?p=23314"},"modified":"2025-11-27T15:29:39","modified_gmt":"2025-11-27T18:29:39","slug":"sejuri-marca-presenca-no-2o-encontro-nacional-de-alta-gestao-nas-politicas-penais-em-brasilia","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/sejuri-marca-presenca-no-2o-encontro-nacional-de-alta-gestao-nas-politicas-penais-em-brasilia\/","title":{"rendered":"SEJURI marca presen\u00e7a no 2\u00ba Encontro Nacional de Alta Gest\u00e3o nas Pol\u00edticas Penais, em Bras\u00edlia"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A Secretaria de Estado de Justi\u00e7a e Reintegra\u00e7\u00e3o Social (SEJURI) participa, nesta quinta-feira (27), do 2\u00ba Encontro Nacional de Alta Gest\u00e3o nas Pol\u00edticas Penais, realizado no audit\u00f3rio Ministro Mozart Victor Russomano, no Tribunal Superior do Trabalho (TST). Representaram Santa Catarina a secret\u00e1ria de Justi\u00e7a e Reintegra\u00e7\u00e3o Social, Danielle Amorim, e o diretor-geral da Pol\u00edcia Penal, Maicon Alves.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Promovido pelo Conselho Nacional de Justi\u00e7a (CNJ) em parceria com a Secretaria Nacional de Pol\u00edticas Penais (SENAPPEN), o encontro reuniu autoridades do Executivo, integrantes do Sistema de Justi\u00e7a, \u00f3rg\u00e3os de controle e especialistas do setor para debater caminhos para o avan\u00e7o das pol\u00edticas penais no pa\u00eds.<\/span><\/p>\n<figure id=\"attachment_23318\" aria-describedby=\"caption-attachment-23318\" style=\"width: 688px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-27-at-14.51.36.jpeg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-23318\" src=\"http:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-27-at-14.51.36-1024x738.jpeg\" alt=\"\" width=\"688\" height=\"496\" srcset=\"https:\/\/sap.sc.gov.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-27-at-14.51.36-1024x738.jpeg 1024w, https:\/\/sap.sc.gov.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-27-at-14.51.36-300x216.jpeg 300w, https:\/\/sap.sc.gov.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-27-at-14.51.36-768x554.jpeg 768w, https:\/\/sap.sc.gov.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-27-at-14.51.36-18x12.jpeg 18w, https:\/\/sap.sc.gov.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-27-at-14.51.36.jpeg 1280w\" sizes=\"(max-width: 688px) 100vw, 688px\" \/><\/a><figcaption id=\"caption-attachment-23318\" class=\"wp-caption-text\">Foto: Divulga\u00e7\u00e3o SENAPPEN<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Entre os principais temas discutidos, ganhou destaque a defini\u00e7\u00e3o de estrat\u00e9gias de financiamento para a execu\u00e7\u00e3o do Plano Pena Justa, al\u00e9m de debates sobre moderniza\u00e7\u00e3o do sistema prisional, fortalecimento da gest\u00e3o e amplia\u00e7\u00e3o de a\u00e7\u00f5es de ressocializa\u00e7\u00e3o. As mesas tem\u00e1ticas abordaram formas de alinhar os instrumentos de planejamento p\u00fablico \u00e0s a\u00e7\u00f5es previstas no plano e tamb\u00e9m discutiram possibilidades de fomento complementar, por meio do Fundo Penitenci\u00e1rio Nacional (Funpen), do BNDES e de outras fontes de financiamento.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A participa\u00e7\u00e3o da SEJURI refor\u00e7a o compromisso de Santa Catarina com a constru\u00e7\u00e3o de um sistema prisional mais eficiente e orientado pela gest\u00e3o qualificada \u2014 pilares essenciais para a reintegra\u00e7\u00e3o social e para o fortalecimento da Seguran\u00e7a P\u00fablica.<\/span><\/p>\n<figure id=\"attachment_23315\" aria-describedby=\"caption-attachment-23315\" style=\"width: 716px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-27-at-14.55.51.jpeg\"><img decoding=\"async\" class=\"wp-image-23315\" src=\"http:\/\/sejuri.sc.gov.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-27-at-14.55.51-1024x606.jpeg\" alt=\"\" width=\"716\" height=\"424\" srcset=\"https:\/\/sap.sc.gov.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-27-at-14.55.51-1024x606.jpeg 1024w, https:\/\/sap.sc.gov.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-27-at-14.55.51-300x178.jpeg 300w, https:\/\/sap.sc.gov.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-27-at-14.55.51-768x455.jpeg 768w, https:\/\/sap.sc.gov.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-27-at-14.55.51-18x12.jpeg 18w, https:\/\/sap.sc.gov.br\/wp-content\/uploads\/2025\/11\/WhatsApp-Image-2025-11-27-at-14.55.51.jpeg 1280w\" sizes=\"(max-width: 716px) 100vw, 716px\" \/><\/a><figcaption id=\"caption-attachment-23315\" class=\"wp-caption-text\">Foto: Divulga\u00e7\u00e3o SENAPPEN<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">O evento contou ainda com a presen\u00e7a de magistrados, entre eles o juiz Caio Berardo, coordenador do GMF, demonstrando a import\u00e2ncia da integra\u00e7\u00e3o entre os poderes na formula\u00e7\u00e3o de pol\u00edticas penais eficazes e sustent\u00e1veis.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado de Justi\u00e7a e Reintegra\u00e7\u00e3o Social (SEJURI) participa, nesta quinta-feira (27), do 2\u00ba Encontro Nacional de Alta Gest\u00e3o nas Pol\u00edticas Penais, realizado no audit\u00f3rio Ministro Mozart Victor Russomano, no Tribunal Superior do Trabalho (TST). Representaram Santa Catarina a secret\u00e1ria de Justi\u00e7a e Reintegra\u00e7\u00e3o Social, Danielle Amorim, e o diretor-geral da Pol\u00edcia Penal, [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":23316,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1315,79,1296,46],"tags":[1336],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 22:59:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/23314"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=23314"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/23314\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/23316"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=23314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=23314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=23314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}