{"id":23987,"date":"2026-02-18T18:51:12","date_gmt":"2026-02-18T21:51:12","guid":{"rendered":"https:\/\/sejuri.sc.gov.br\/?p=23987"},"modified":"2026-02-18T18:51:12","modified_gmt":"2026-02-18T21:51:12","slug":"inteligencia-contra-o-crime-organizado-policia-penal-de-sc-lanca-curso-e-abre-vagas-para-todas-as-forcas","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/inteligencia-contra-o-crime-organizado-policia-penal-de-sc-lanca-curso-e-abre-vagas-para-todas-as-forcas\/","title":{"rendered":"Intelig\u00eancia contra o crime organizado: Pol\u00edcia Penal de SC lan\u00e7a curso e abre vagas para todas as for\u00e7as"},"content":{"rendered":"<p style=\"text-align: justify;\"><i><span style=\"font-weight: 400;\">A Secretaria de Estado de Justi\u00e7a e Reintegra\u00e7\u00e3o Social de Santa Catarina, por meio da Academia de Administra\u00e7\u00e3o Prisional e Socioeducativa, lan\u00e7ou o Curso de Intelig\u00eancia Penitenci\u00e1ria (CIP), uma forma\u00e7\u00e3o estrat\u00e9gica voltada ao fortalecimento do enfrentamento ao crime organizado dentro e fora das unidades prisionais.<\/span><\/i><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Com in\u00edcio previsto para 9 de mar\u00e7o, na cidade de Chapec\u00f3, o curso representa um marco no processo de profissionaliza\u00e7\u00e3o da Pol\u00edcia Penal catarinense ao estruturar, de forma t\u00e9cnica e sistematizada, a atua\u00e7\u00e3o na \u00e1rea de intelig\u00eancia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A capacita\u00e7\u00e3o \u00e9 direcionada a policiais penais efetivos e tamb\u00e9m est\u00e1 aberta \u00e0 participa\u00e7\u00e3o de integrantes de outras for\u00e7as de seguran\u00e7a, refor\u00e7ando o car\u00e1ter integrado das a\u00e7\u00f5es de intelig\u00eancia no Estado. Ao todo, ser\u00e3o disponibilizadas 20 vagas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A forma\u00e7\u00e3o possui natureza operacional e estrat\u00e9gica, com avalia\u00e7\u00f5es te\u00f3ricas e pr\u00e1ticas, exigindo elevado n\u00edvel t\u00e9cnico dos participantes. Entre os crit\u00e9rios est\u00e3o habilita\u00e7\u00f5es espec\u00edficas, experi\u00eancia funcional e investiga\u00e7\u00e3o social, o que refor\u00e7a a responsabilidade da atua\u00e7\u00e3o na \u00e1rea.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">A proposta \u00e9 qualificar servidores para produ\u00e7\u00e3o, an\u00e1lise e gest\u00e3o de informa\u00e7\u00f5es sens\u00edveis, ampliando a capacidade do Estado de antecipar riscos, desarticular a\u00e7\u00f5es criminosas e subsidiar decis\u00f5es estrat\u00e9gicas no sistema prisional.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Em manifesta\u00e7\u00e3o institucional, a secret\u00e1ria destaca que a intelig\u00eancia \u00e9 uma das principais ferramentas no combate \u00e0s organiza\u00e7\u00f5es criminosas. Segundo ela, investir na forma\u00e7\u00e3o especializada dos policiais penais \u00e9 fortalecer a seguran\u00e7a p\u00fablica como um todo, uma vez que o sistema prisional \u00e9 ponto estrat\u00e9gico no enfrentamento \u00e0s fac\u00e7\u00f5es e na interrup\u00e7\u00e3o de fluxos criminosos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">As inscri\u00e7\u00f5es seguem abertas at\u00e9 22 de fevereiro, com resultado final previsto para o dia 27. As aulas ser\u00e3o realizadas entre 9 e 27 de mar\u00e7o.\u00a0 <\/span><span style=\"font-weight: 400;\">Acesse o link do edital\u00a0<a href=\"https:\/\/sejuri.sc.gov.br\/download\/01_edital-7\/\" target=\"_blank\" rel=\"noopener\">aqui<\/a>.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado de Justi\u00e7a e Reintegra\u00e7\u00e3o Social de Santa Catarina, por meio da Academia de Administra\u00e7\u00e3o Prisional e Socioeducativa, lan\u00e7ou o Curso de Intelig\u00eancia Penitenci\u00e1ria (CIP), uma forma\u00e7\u00e3o estrat\u00e9gica voltada ao fortalecimento do enfrentamento ao crime organizado dentro e fora das unidades prisionais. Com in\u00edcio previsto para 9 de mar\u00e7o, na cidade de [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":23988,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1315,1296,46],"tags":[1336],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 23:39:38","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/23987"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=23987"}],"version-history":[{"count":1,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/23987\/revisions"}],"predecessor-version":[{"id":23989,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/23987\/revisions\/23989"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/23988"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=23987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=23987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=23987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}