{"id":24143,"date":"2026-03-10T15:24:24","date_gmt":"2026-03-10T18:24:24","guid":{"rendered":"https:\/\/sejuri.sc.gov.br\/?p=24143"},"modified":"2026-03-10T15:24:24","modified_gmt":"2026-03-10T18:24:24","slug":"projeto-da-sejuri-e-selecionado-para-concorrer-ao-premio-brasilgov-2026","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/projeto-da-sejuri-e-selecionado-para-concorrer-ao-premio-brasilgov-2026\/","title":{"rendered":"Projeto da Sejuri \u00e9 selecionado para concorrer ao Pr\u00eamio BrasilGov 2026"},"content":{"rendered":"<p style=\"text-align: justify;\"><i><span style=\"font-weight: 400;\">A Secretaria de Estado da Justi\u00e7a e Reintegra\u00e7\u00e3o Social (Sejuri) teve o projeto \u201cSegunda Chance\u201d selecionado para concorrer ao Pr\u00eamio BrasilGov 2026, uma das principais premia\u00e7\u00f5es da Am\u00e9rica Latina voltadas \u00e0 inova\u00e7\u00e3o na gest\u00e3o p\u00fablica. A iniciativa integra a programa\u00e7\u00e3o do BrasilGov Summit 2026, evento que re\u00fane lideran\u00e7as do setor p\u00fablico e empresas de tecnologia para debater solu\u00e7\u00f5es que modernizam a administra\u00e7\u00e3o p\u00fablica.<\/span><\/i><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Desenvolvido no sistema prisional catarinense, o projeto consolida o trabalho prisional como pol\u00edtica p\u00fablica de reintegra\u00e7\u00e3o social. A iniciativa integra a estrat\u00e9gia de gest\u00e3o da secret\u00e1ria de Estado da Justi\u00e7a e Reintegra\u00e7\u00e3o Social, Danielle Amorim Silva, no governo Jorginho Mello.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Em 2025, o trabalho realizado por pessoas privadas de liberdade gerou valores expressivos em Santa Catarina, mais de R$ 85 milh\u00f5es foram atribu\u00eddos diretamente aos apenados e R$ 33 milh\u00f5es correspondem ao percentual destinado ao Estado. Conforme previsto na Lei de Execu\u00e7\u00e3o Penal, 25% da remunera\u00e7\u00e3o dos apenados deve ser utilizada como ressarcimento pelos custos da execu\u00e7\u00e3o da pena, enquanto 75% permanecem com os pr\u00f3prios trabalhadores do sistema prisional.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Os recursos ficam vinculados \u00e0s contas das unidades prisionais e s\u00e3o administrados pelo Estado, com destina\u00e7\u00e3o aos pr\u00f3prios apenados, conforme determina a legisla\u00e7\u00e3o.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Santa Catarina tamb\u00e9m se destaca nacionalmente pelo n\u00famero de pessoas privadas de liberdade inseridas em atividades produtivas: mais de 10 mil apenados trabalham atualmente no sistema prisional catarinense.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">O modelo \u00e9 sustentado pela Lei Complementar n\u00ba 809\/2022, que regulamenta as parcerias para o trabalho prisional e permite contratos com empresas de 6 meses a 15 anos, com possibilidade de prorroga\u00e7\u00e3o, garantindo seguran\u00e7a jur\u00eddica e estabilidade para o poder p\u00fablico e parceiros privados.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Para a secret\u00e1ria Danielle Amorim Silva, o reconhecimento nacional refor\u00e7a a import\u00e2ncia de pol\u00edticas p\u00fablicas que ampliem oportunidades dentro do sistema prisional.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u201c<\/span><i><span style=\"font-weight: 400;\">O trabalho \u00e9 uma das ferramentas mais eficazes de transforma\u00e7\u00e3o social. O projeto Segunda Chance mostra que \u00e9 poss\u00edvel unir responsabilidade fiscal, efici\u00eancia na gest\u00e3o p\u00fablica e oportunidades reais de reintegra\u00e7\u00e3o\u201d,<\/span><\/i><span style=\"font-weight: 400;\"> destacou.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">O Pr\u00eamio BrasilGov reconhece iniciativas que transformam a gest\u00e3o p\u00fablica por meio da inova\u00e7\u00e3o e da tecnologia. A sele\u00e7\u00e3o do projeto refor\u00e7a Santa Catarina como refer\u00eancia nacional em pol\u00edticas de reintegra\u00e7\u00e3o social e ressocializa\u00e7\u00e3o no sistema prisional.<\/span><\/p>\n<p style=\"text-align: justify;\">","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado da Justi\u00e7a e Reintegra\u00e7\u00e3o Social (Sejuri) teve o projeto \u201cSegunda Chance\u201d selecionado para concorrer ao Pr\u00eamio BrasilGov 2026, uma das principais premia\u00e7\u00f5es da Am\u00e9rica Latina voltadas \u00e0 inova\u00e7\u00e3o na gest\u00e3o p\u00fablica. A iniciativa integra a programa\u00e7\u00e3o do BrasilGov Summit 2026, evento que re\u00fane lideran\u00e7as do setor p\u00fablico e empresas de tecnologia [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":24144,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296,46],"tags":[1336],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 23:39:33","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/24143"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=24143"}],"version-history":[{"count":1,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/24143\/revisions"}],"predecessor-version":[{"id":24145,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/24143\/revisions\/24145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/24144"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=24143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=24143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=24143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}