{"id":24237,"date":"2026-03-11T11:54:14","date_gmt":"2026-03-11T14:54:14","guid":{"rendered":"https:\/\/sejuri.sc.gov.br\/?p=24237"},"modified":"2026-03-11T11:54:14","modified_gmt":"2026-03-11T14:54:14","slug":"policiais-penais-prestam-socorro-a-vitimas-de-grave-acidente-na-br-282","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/policiais-penais-prestam-socorro-a-vitimas-de-grave-acidente-na-br-282\/","title":{"rendered":"Policiais penais prestam socorro a v\u00edtimas de grave acidente na BR-282"},"content":{"rendered":"<p>Policiais penais de Santa Catarina prestaram socorro \u00e0s v\u00edtimas de um grave acidente de tr\u00e2nsito registrado na tarde do dia 10 de mar\u00e7o de 2026, por volta das 16h50, na BR-282, nas proximidades do munic\u00edpio de Bom Retiro.<\/p>\n<p>A equipe se deslocava em dire\u00e7\u00e3o \u00e0 Unidade de Seguran\u00e7a M\u00e1xima (USM), em S\u00e3o Crist\u00f3v\u00e3o do Sul, quando se deparou com a ocorr\u00eancia envolvendo um ve\u00edculo que saiu da pista e capotou ap\u00f3s colidir com um caminh\u00e3o, que deixou o local. Diante da situa\u00e7\u00e3o, os policiais penais interromperam imediatamente o deslocamento da viatura para auxiliar as v\u00edtimas.<\/p>\n<p>Os servidores prestaram os primeiros atendimentos, realizaram a sinaliza\u00e7\u00e3o da rodovia e organizaram o tr\u00e2nsito at\u00e9 a chegada das equipes de resgate do Corpo de Bombeiros Militar e do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (SAMU).<\/p>\n<p>No ve\u00edculo estavam seis ocupantes: tr\u00eas adultos e tr\u00eas crian\u00e7as. Os ocupantes do banco dianteiro conseguiram sair do ve\u00edculo por meios pr\u00f3prios e apresentavam ferimentos leves. J\u00e1 os passageiros que estavam no banco traseiro sofreram ferimentos mais graves ap\u00f3s serem ejetados durante o capotamento.<\/p>\n<p>As crian\u00e7as foram encaminhadas pelo SAMU ao Hospital Nossa Senhora das Gra\u00e7as, em Bom Retiro, enquanto outras v\u00edtimas foram conduzidas pelas equipes de resgate para atendimento m\u00e9dico.<\/p>\n<p>Ap\u00f3s o socorro \u00e0s v\u00edtimas, os bombeiros realizaram a retirada do ve\u00edculo da pista e a limpeza da via para restabelecer a seguran\u00e7a no local.<\/p>\n<p>Os policiais penais permaneceram no local prestando apoio at\u00e9 a finaliza\u00e7\u00e3o da ocorr\u00eancia. Participaram da a\u00e7\u00e3o os policiais penais Lindongilson Fran\u00e7a Ferreira, Adilson da Silva e Rodrigo Alves Teixeira.<\/p>\n<p>De acordo com o Corpo de Bombeiros, a atua\u00e7\u00e3o r\u00e1pida da equipe foi fundamental para o atendimento inicial da ocorr\u00eancia, demonstrando o compromisso dos servidores com a prote\u00e7\u00e3o da vida e o apoio \u00e0 comunidade.<\/p>","protected":false},"excerpt":{"rendered":"<p>Policiais penais de Santa Catarina prestaram socorro \u00e0s v\u00edtimas de um grave acidente de tr\u00e2nsito registrado na tarde do dia 10 de mar\u00e7o de 2026, por volta das 16h50, na BR-282, nas proximidades do munic\u00edpio de Bom Retiro. A equipe se deslocava em dire\u00e7\u00e3o \u00e0 Unidade de Seguran\u00e7a M\u00e1xima (USM), em S\u00e3o Crist\u00f3v\u00e3o do Sul, [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":24239,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296,46],"tags":[1336],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 23:39:39","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/24237"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=24237"}],"version-history":[{"count":1,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/24237\/revisions"}],"predecessor-version":[{"id":24238,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/24237\/revisions\/24238"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/24239"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=24237"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=24237"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=24237"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}