{"id":2818,"date":"2021-03-16T19:16:05","date_gmt":"2021-03-16T19:16:05","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2021\/03\/16\/oficina-no-casep-de-cacador-desenho-de-perspectiva-e-proporcao\/"},"modified":"2021-03-16T19:16:05","modified_gmt":"2021-03-16T19:16:05","slug":"oficina-no-casep-de-cacador-desenho-de-perspectiva-e-proporcao","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/oficina-no-casep-de-cacador-desenho-de-perspectiva-e-proporcao\/","title":{"rendered":"Oficina no Casep de Ca\u00e7ador: Desenho de Perspectiva e Propor\u00e7\u00e3o"},"content":{"rendered":"<p>O desenho t\u00e9cnico como poss\u00edvel oportunidade de gera\u00e7\u00e3o de renda ap\u00f3s cumprimento de medida socioeducativa.<\/p>\n<p style=\"text-align: justify;\">O Casep de Ca\u00e7ador atrav\u00e9s do Projeto Comunic\u2019arte, atua com atividades art\u00edsticas fomentando a criatividade e a express\u00e3o, utilizando a arte como ferramenta de ressocializa\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Atividades pedag\u00f3gicas que v\u00e3o al\u00e9m da ludicidade, que desenvolvam capacidades motoras e de express\u00f5es art\u00edsticas, por\u00e9m, direcionando esta energia inata da juventude, com t\u00e9cnicas de produ\u00e7\u00f5es art\u00edsticas variadas como por exemplo o desenho. Tendo como amparo o Art. 31, par\u00e1grafo 2, do decreto n\u00ba 99.710\\1990 a<\/p>\n<p style=\"text-align: justify;\">Conven\u00e7\u00e3o sobre os Direitos da Crian\u00e7a; \u201c<em>Os Estados-Partes respeitar\u00e3o e promover\u00e3o o direito da crian\u00e7a de participar plenamente da vida cultural e art\u00edstica<\/em>&#8230;\u201d.<\/p>\n<p style=\"text-align: justify;\">Deste modo no dia 02 de Mar\u00e7o do presente ano, a unidade de Ca\u00e7ador, aplicou a oficina Desenho de Perspectiva e Propor\u00e7\u00e3o, com a atividade que utilizou m\u00e9todos e t\u00e9cnicas apuradas como; profundidade, arestas, ponto de fuga, linhas convergentes e no\u00e7\u00f5es de perspectiva. Os adolescentes se surpreenderam com seus resultados j\u00e1 que muitos relataram nunca terem desenhado algo \u201ct\u00e3o realista\u201d. Isto posto o Casep de Ca\u00e7ador vem demonstrando que a arte vai muito al\u00e9m de lazer mas pode sim servir como subs\u00eddio para quem sabe ser um alternativa de profiss\u00e3o futura p\u00f3s internamento.<\/p><\/p>","protected":false},"excerpt":{"rendered":"<p>O desenho t\u00e9cnico como poss\u00edvel oportunidade de gera\u00e7\u00e3o de renda ap\u00f3s cumprimento de medida socioeducativa. O Casep de Ca\u00e7ador atrav\u00e9s do Projeto Comunic\u2019arte, atua com atividades art\u00edsticas fomentando a criatividade e a express\u00e3o, utilizando a arte como ferramenta de ressocializa\u00e7\u00e3o. Atividades pedag\u00f3gicas que v\u00e3o al\u00e9m da ludicidade, que desenvolvam capacidades motoras e de express\u00f5es art\u00edsticas, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:12:47","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2818"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2818"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2818\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}