{"id":2897,"date":"2022-02-04T21:26:02","date_gmt":"2022-02-04T21:26:02","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2022\/02\/04\/casep-de-joinville-oferece-atividades-diversificadas-aos-socioeducandos\/"},"modified":"2022-02-04T21:26:02","modified_gmt":"2022-02-04T21:26:02","slug":"casep-de-joinville-oferece-atividades-diversificadas-aos-socioeducandos","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/casep-de-joinville-oferece-atividades-diversificadas-aos-socioeducandos\/","title":{"rendered":"Casep de Joinville oferece atividades diversificadas aos socioeducandos"},"content":{"rendered":"<p><strong>OFICINA PRIMEIROS PASSOS NA M\u00daSICA <\/strong><\/p>\n<p style=\"text-align: justify;\">\u201cA m\u00fasica \u00e9 um dos caminhos de transforma\u00e7\u00e3o social\u201d. Neste sentido, o INECES \u2013 Instituto Nacional de Erradica\u00e7\u00e3o Social da Car\u00eancia Escolar e Social e seus colaboradores do Casep de Joinville promoveram a \u201cOficina Primeiros Passos na M\u00fasica\u201d aos socioeducandos que cumprem medida socioeducativa na Unidade.<\/p>\n<p style=\"text-align: justify;\">A atividade foi ministrada por dois estudantes de psicologia da Faculdade Anhanguera de Joinville.<\/p>\n<p style=\"text-align: justify;\">Na oficina, os socioeducandos vivenciaram, na pr\u00e1tica, o contato com viol\u00e3o e uma bateria eletr\u00f4nica. Falaram sobre seus gostos musicais, contaram as experi\u00eancias que tiveram com a m\u00fasica e aprenderam sobre os conceitos b\u00e1sicos e musicais dos dois instrumentos. Para a maioria foi o primeiro contato com o viol\u00e3o e bateria eletr\u00f4nica e renderam os primeiros acordes e as primeiras batidas.<\/p>\n<\/p>\n<p>&nbsp;<\/p>\n<p><strong>REESTRUTURA\u00c7\u00c3O DA HORTA ORG\u00c2NICA <\/strong><\/p>\n<p style=\"text-align: justify;\">Os adolescentes do Casep de Joinville deram in\u00edcio ao processo de modifica\u00e7\u00e3o e reestrutura\u00e7\u00e3o da horta org\u00e2nica da Unidade. A horta org\u00e2nica segue os princ\u00edpios da agroecologia, o que implica a exclus\u00e3o de qualquer uso de produtos qu\u00edmicos e defensivos, visando a produ\u00e7\u00e3o de alimentos saud\u00e1veis e sustent\u00e1veis.<\/p>\n<p style=\"text-align: justify;\">O cultivo de alimentos sem defensivos tem o objetivo de estimular a agricultura familiar e urbana, incentivando a\u00e7\u00f5es comunit\u00e1rias e favorecendo o meio ambiente, al\u00e9m de que esta pr\u00e1tica contribui na forma\u00e7\u00e3o de pessoas mais conscientes, \u00e9ticas e solid\u00e1rias.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-752\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2022\/02\/Foto_horta-72d.jpg\" alt=\"Foto horta\" width=\"567\" height=\"404\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong>DOA\u00c7\u00c3O DE UM TEAR&nbsp;<\/strong><\/p>\n<p style=\"text-align: justify;\">O Casep de Joinville recebeu da Pastoral Carcer\u00e1ria a doa\u00e7\u00e3o de um tear para ser utilizado na Unidade. Tear \u00e9 um aparelho mec\u00e2nico ou eletromec\u00e2nico empregado para fins de tecelagem.&nbsp;<\/p>\n<p style=\"text-align: justify;\">Inicialmente a m\u00e1quina ser\u00e1 utilizada para produzir tapetes e, futuramente, poder\u00e1 ser usada na produ\u00e7\u00e3o de outras pe\u00e7as de tecido.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-753\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2022\/02\/Foto_tear-dcd.jpg\" alt=\"Foto tear\" width=\"567\" height=\"323\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>","protected":false},"excerpt":{"rendered":"<p>OFICINA PRIMEIROS PASSOS NA M\u00daSICA \u201cA m\u00fasica \u00e9 um dos caminhos de transforma\u00e7\u00e3o social\u201d. Neste sentido, o INECES \u2013 Instituto Nacional de Erradica\u00e7\u00e3o Social da Car\u00eancia Escolar e Social e seus colaboradores do Casep de Joinville promoveram a \u201cOficina Primeiros Passos na M\u00fasica\u201d aos socioeducandos que cumprem medida socioeducativa na Unidade. A atividade foi ministrada [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":751,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 07:30:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2897"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=2897"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/2897\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=2897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=2897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=2897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}