{"id":885,"date":"2022-11-01T20:52:47","date_gmt":"2022-11-01T20:52:47","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2022\/11\/01\/superintendencia-psicossocial-e-saude-do-dease-divulga-calendario-da-saude-para-o-mes-de-novembro-2\/"},"modified":"2022-11-01T20:52:47","modified_gmt":"2022-11-01T20:52:47","slug":"superintendencia-psicossocial-e-saude-do-dease-divulga-calendario-da-saude-para-o-mes-de-novembro-2","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/superintendencia-psicossocial-e-saude-do-dease-divulga-calendario-da-saude-para-o-mes-de-novembro-2\/","title":{"rendered":"Superintend\u00eancia Psicossocial e Sa\u00fade do Dease divulga calend\u00e1rio da sa\u00fade para o m\u00eas de novembro"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>CALENDARIO M\u00caS DE NOVEMBRO<\/strong><\/p>\n<p style=\"text-align: center;\">14\/11 &#8211; Dia Mundial do Diabetes<\/p>\n<p style=\"text-align: center;\">16\/11 &#8211; Dia Nacional dos Ostomizados<\/p>\n<p style=\"text-align: center;\">17\/11 &#8211; Dia Mundial da Prematuridade<\/p>\n<p style=\"text-align: center;\">21\/11 &#8211; Dia Nacional da Homeopatia<\/p>\n<p><strong>&nbsp;<\/strong><strong>&nbsp;<\/strong><\/p>\n<p><strong style=\"font-size: 16px;\">NOVEMBRO AZUL \u2013 Sa\u00fade do Homem<\/strong><\/p>\n<\/p>\n<p style=\"text-align: justify;\">A campanha mundial do Novembro Azul procura conscientizar os homens sobre os cuidados com a sa\u00fade, especialmente na preven\u00e7\u00e3o do c\u00e2ncer de pr\u00f3stata, um dos mais frequentes entre os brasileiros. De acordo com o Instituto Nacional de C\u00e2ncer (INCA), o c\u00e2ncer de pr\u00f3stata \u00e9 o segundo mais comum entre os homens no Brasil (atr\u00e1s do c\u00e2ncer de pele n\u00e3o-melanoma). O total estimado de novos casos de c\u00e2ncer de pr\u00f3stata \u00e9 de 65.840 (dados de 2020), que corresponde a 29,2% dos tumores incidentes no sexo masculino. Em valores absolutos e considerando ambos os sexos, \u00e9 o segundo tipo mais comum. O Atlas de Mortalidade por C\u00e2ncer, tamb\u00e9m produzido pelo INCA, aponta 15.983 mortes por c\u00e2ncer de pr\u00f3stata, em 2019. Podemos destacar dois exames com importante papel para o diagn\u00f3stico da doen\u00e7a: o exame de sangue, por meio do Ant\u00edgeno Prost\u00e1tico Espec\u00edfico (PSA), e o exame de toque retal, ambos cobertos pelos planos de sa\u00fade.<\/p>\n<p style=\"text-align: justify;\">De acordo com o Minist\u00e9rio da Sa\u00fade, o c\u00e2ncer de pr\u00f3stata, inicialmente, pode n\u00e3o apresentar sintomas. Mas quando ele se manifesta, os sinais mais comuns s\u00e3o:<\/p>\n<p style=\"text-align: justify;\">&#8211; Dificuldade de urinar;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n<p style=\"text-align: justify;\">&#8211; Demora em come\u00e7ar e terminar de urinar;<\/p>\n<p style=\"text-align: justify;\">&#8211; Sangue na urina;<\/p>\n<p style=\"text-align: justify;\">&#8211; Diminui\u00e7\u00e3o do jato de urina; e<\/p>\n<p style=\"text-align: justify;\">&#8211; Necessidade de urinar mais vezes durante o dia ou \u00e0 noite.<\/p>\n<p style=\"text-align: justify;\">Na presen\u00e7a de sinais e sintomas, recomenda-se procurar uma unidade m\u00e9dica para realizar exames com um m\u00e9dico especialista.<\/p>\n<p style=\"text-align: justify;\">O diagn\u00f3stico precoce do c\u00e2ncer de pr\u00f3stata \u00e9 fundamental para maior chance de recupera\u00e7\u00e3o. Mesmo na aus\u00eancia de sintomas, homens a partir dos 45 anos com fatores de risco, ou 50 anos sem estes fatores, devem ir ao urologista para conversar sobre o exame de toque retal, que permite ao m\u00e9dico avaliar altera\u00e7\u00f5es da gl\u00e2ndula, como endurecimento e presen\u00e7a de n\u00f3dulos suspeitos e sobre o exame de sangue PSA. Outros exames poder\u00e3o ser solicitados se houver suspeita de c\u00e2ncer, como as bi\u00f3psias, que retiram fragmentos da pr\u00f3stata para an\u00e1lise, guiadas pelo ultrassom transretal.<\/p>\n<p style=\"text-align: justify;\">De acordo com o INCA, uma dieta rica em frutas, verduras, legumes, gr\u00e3os e cereais integrais e com menos gordura, principalmente as de origem animal, ajuda a diminuir o risco de c\u00e2ncer, como tamb\u00e9m de outras doen\u00e7as cr\u00f4nicas n\u00e3o transmiss\u00edveis. Nesse sentido, outros h\u00e1bitos saud\u00e1veis tamb\u00e9m s\u00e3o recomendados, como fazer no m\u00ednimo 30 minutos di\u00e1rios de atividade f\u00edsica, manter o peso adequado \u00e0 altura, identificar e tratar adequadamente a hipertens\u00e3o, diabetes e problemas de colesterol, diminuir o consumo de \u00e1lcool e n\u00e3o fumar.<\/p>\n<p style=\"text-align: justify;\">Vale ressaltar que al\u00e9m do c\u00e2ncer de pr\u00f3stata as principais causas de mortalidade da popula\u00e7\u00e3o masculina s\u00e3o:<\/p>\n<p style=\"text-align: justify;\">&#8211; Causas externas de morbidade e mortalidade;<\/p>\n<p style=\"text-align: justify;\">&#8211; Doen\u00e7as do aparelho circulat\u00f3rio;<\/p>\n<p style=\"text-align: justify;\">&#8211; Neoplasias (tumores);<\/p>\n<p style=\"text-align: justify;\">&#8211; Doen\u00e7as do aparelho digestivo; e<\/p>\n<p style=\"text-align: justify;\">&#8211; Algumas doen\u00e7as infecciosas e parasit\u00e1rias.<\/p>\n<p style=\"text-align: justify;\">Por isso n\u00e3o perca tempo e deixe o preconceito de lado. Se voc\u00ea j\u00e1 estiver na faixa recomendada para a realiza\u00e7\u00e3o do exame procure um urologista e converse sobre o tema. A detec\u00e7\u00e3o e o tratamento precoces podem salvar vidas.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-877\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2022\/11\/Por_que_os_homens_adoecem-f3a.jpg\" alt=\"Por que os homens adoecem\" width=\"334\" height=\"661\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong style=\"font-size: 16px;\">DIA MUNDIAL DO DIABETES<\/strong><\/p>\n<p style=\"text-align: justify;\">Comemorado desde o dia 14 de novembro de 1991, data de anivers\u00e1rio de Sir Frederick Banting, co-descobridor da insulina, juntamente com Charles Best, a data foi escolhida pela Federa\u00e7\u00e3o Internacional de Diabetes junto \u00e0 Organiza\u00e7\u00e3o Mundial de Sa\u00fade para conscientizar o mundo sobre o reflexo do diabetes na sa\u00fade e mortalidade da popula\u00e7\u00e3o. Para as campanhas dos anos de 2021 a 2023 o tema adotado \u00e9 \u201cAcesso aos Cuidados da Diabetes\u201d.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-878\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2022\/11\/Dia_mundial_do_diabetes-58d.jpg\" alt=\"Dia mundial do diabetes\" width=\"251\" height=\"150\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>\n<p style=\"text-align: justify;\">Mundialmente estima-se que 537 milh\u00f5es de pessoas vivam com Diabetes, sendo a maioria desses casos a Diabetes Tipo 2, que \u00e9 amplamente evit\u00e1vel por meio de atividade f\u00edsica regular, uma dieta saud\u00e1vel e equilibrada e a promo\u00e7\u00e3o de h\u00e1bitos saud\u00e1veis. &nbsp;Assim, as fam\u00edlias t\u00eam um papel fundamental a desempenhar na abordagem dos fatores de risco modific\u00e1veis para essa doen\u00e7a e devem receber educa\u00e7\u00e3o, recursos e h\u00e1bitos para ter um estilo de vida saud\u00e1vel.<\/p>\n<p>&nbsp;<\/p>\n<p><strong style=\"font-size: 16px;\">DIA NACIONAL DOS OSTOMIZADOS<\/strong><\/p>\n<p style=\"text-align: justify;\">Ostomia ou estomia \u00e9 um procedimento realizado com o objetivo de construir um novo caminho para a elimina\u00e7\u00e3o de urina e fezes. V\u00e1rias condi\u00e7\u00f5es de sa\u00fade exigem uma cirurgia para a realiza\u00e7\u00e3o de estomas, tais como, doen\u00e7as cr\u00f4nico-degenerativas, entre elas o c\u00e2ncer, Doen\u00e7a de Chagas, doen\u00e7as inflamat\u00f3rias (Retocolite Ulcerativa Inespec\u00edfica e Doen\u00e7a de Crohn), malforma\u00e7\u00f5es cong\u00eanitas (\u00e2nus imperfurado, mielomeningocele), traumas abdominoperineais (ferimento por armas de fogo ou brancas, acidente automobil\u00edstico e outros), doen\u00e7as neurol\u00f3gicas, entre outras. Ela pode ocorrer nas diferentes faixas et\u00e1rias, desde neonatos at\u00e9 idosos.<\/p>\n<p style=\"text-align: justify;\">As estomias podem ser tempor\u00e1rias, que ap\u00f3s um tempo pr\u00e9-determinado ser\u00e3o fechadas por meio de nova interven\u00e7\u00e3o cir\u00fargica ou definitivas, quando a pessoa conviver\u00e1 com ela durante sua vida.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-879\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2022\/11\/Ostomizados-6f9.jpg\" alt=\"Ostomizados\" width=\"217\" height=\"177\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>\n<p style=\"text-align: justify;\">A designa\u00e7\u00e3o do tipo de estomia \u00e9 definida pelo tipo de \u00f3rg\u00e3o ou v\u00edscera que ser\u00e1 exposto: colostomia (c\u00f3lon), ileostomia (\u00edleo), gastrostomia (est\u00f4mago), nefrostomia (rim), ureterostomia (ureter), vesicostomia (bexiga), cistostomia (bexiga com uso de cateter) ou traqueostomia (traqu\u00e9ia), entre outras. A fun\u00e7\u00e3o da estomia varia de acordo com o tipo de \u00f3rg\u00e3o ou v\u00edscera exposta, podendo ser para elimina\u00e7\u00e3o (intestinais e urin\u00e1rias), respira\u00e7\u00e3o (traqueostomia) ou alimenta\u00e7\u00e3o (gastrostomia), por exemplo.<\/p>\n<p style=\"text-align: justify;\">Independentemente de suas caracter\u00edsticas, a realiza\u00e7\u00e3o do estoma \u00e9 sempre um acontecimento traum\u00e1tico, uma vez que o estoma acarreta mudan\u00e7as que repercutir\u00e3o em todos os n\u00edveis da vida da pessoa, tais como: necessidade de realiza\u00e7\u00e3o do autocuidado com o estoma, aquisi\u00e7\u00e3o de material apropriado para a conten\u00e7\u00e3o das fezes ou urina, adequa\u00e7\u00e3o alimentar, conviv\u00eancia com a perda do controle da contin\u00eancia intestinal ou vesical, elimina\u00e7\u00e3o dos odores, altera\u00e7\u00e3o da imagem corporal, altera\u00e7\u00f5es nas atividades sociais, sexuais e, inclusive, nas cotidianas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-880\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2022\/11\/Tipos_de_estomia-1f9.jpg\" alt=\"Tipos de estomia\" width=\"580\" height=\"178\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong style=\"font-size: 16px;\">DIA MUNDIAL DA PREMATURIDADE<\/strong><\/p>\n<p style=\"text-align: justify;\">O Dia Mundial da Prematuridade \u00e9 comemorado, desde 2008, no dia 17 de novembro e tornou-se um movimento intercontinental no qual in\u00fameros indiv\u00edduos e organiza\u00e7\u00f5es de mais de 100 pa\u00edses unem for\u00e7as com atividades, eventos especiais e se comprometem com a a\u00e7\u00e3o para ajudar a abordar a quest\u00e3o do nascimento prematuro e melhorar a situa\u00e7\u00e3o dos beb\u00eas e de suas fam\u00edlias.<\/p>\n<p style=\"text-align: justify;\">\u00c9 preciso chamar a aten\u00e7\u00e3o da popula\u00e7\u00e3o, dos governantes, dos gestores p\u00fablicos, celebridades e influenciadores para a import\u00e2ncia do tema, refletir sobre a qualidade do atendimento oferecido aos prematuros e \u00e0s suas fam\u00edlias e clamar por pol\u00edticas p\u00fablicas de preven\u00e7\u00e3o, humaniza\u00e7\u00e3o do cuidado e por tratamentos adequados e de alcance igualit\u00e1rio.<\/p>\n<p style=\"text-align: justify;\">O Brasil \u00e9 campe\u00e3o em cirurgias ces\u00e1reas, boa parte agendadas sem indica\u00e7\u00e3o cl\u00ednica, o que pode acarretar prematuridade. Segundo dados divulgados pela Alian\u00e7a Nacional para o Parto Seguro e Respeitoso, o Brasil registrou 300 mil nascimentos prematuros em 2019, sendo o 10\u00ba pa\u00eds no ranking mundial de prematuridade. Cabe destacar tamb\u00e9m que 11,7% dos partos ocorrem antes das 37 semanas de gesta\u00e7\u00e3o no pa\u00eds. A Alian\u00e7a re\u00fane em torno de 52 entidades, incluindo a ANS, dispostas a atuar em prol da redu\u00e7\u00e3o da mortalidade materna e neonatal e da garantia de direitos b\u00e1sicos para o parto e para o nascimento seguro no pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">O beb\u00ea que nasce com menos de 37 semanas de gesta\u00e7\u00e3o (36 semanas e 6 dias) \u00e9 considerado prematuro, ou pr\u00e9-termo. No Brasil, o nascimento de beb\u00eas prematuros corresponde a 12,4% dos nascidos vivos, de acordo com dados do Sistema de Informa\u00e7\u00f5es Sobre Nascidos Vivos (Sinasc) e do Minist\u00e9rio da Sa\u00fade.<\/p>\n<p style=\"text-align: justify;\">A prematuridade aumenta a chance de interna\u00e7\u00f5es dos beb\u00eas em UTI, pois \u00e9 na fase final da gesta\u00e7\u00e3o que o sistema cardiorrespirat\u00f3rio amadurece. Sendo assim, beb\u00eas prematuros perdem a oportunidade de estarem mais preparados para lidar com a adapta\u00e7\u00e3o \u00e0 vida fora do \u00fatero. Al\u00e9m disso, podem desenvolver outros problemas, tais como, asma e alergias.<\/p>\n<p style=\"text-align: justify;\">A preven\u00e7\u00e3o da prematuridade se inicia antes mesmo da gesta\u00e7\u00e3o, com o planejamento familiar adequado, seguido do acompanhamento pr\u00e9-natal, que busca assegurar o desenvolvimento da gesta\u00e7\u00e3o, permitindo o parto de um rec\u00e9m-nascido saud\u00e1vel, sem impacto para a sa\u00fade materna, inclusive abordando aspectos psicossociais e atividades educativas e preventivas.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-881\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2022\/11\/Prematuridade-fcb.jpg\" alt=\"Prematuridade\" width=\"187\" height=\"169\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><strong style=\"font-size: 16px;\">DIA NACIONAL DE COMBATE \u00c0 TUBERCULOSE<\/strong><\/p>\n<p style=\"text-align: justify;\">A tuberculose \u00e9 uma doen\u00e7a infectocontagiosa que afeta principalmente os pulm\u00f5es, mas tamb\u00e9m pode acometer \u00f3rg\u00e3os como ossos, rins e meninges (membranas que envolvem o c\u00e9rebro).<\/p>\n<p style=\"text-align: justify;\">A data foi criada em 1982 pela OMS &#8211; Organiza\u00e7\u00e3o Mundial da Sa\u00fade em homenagem aos 100 anos do an\u00fancio do descobrimento do bacilo causador da tuberculose. Segundo estimativas da OMS, um ter\u00e7o da popula\u00e7\u00e3o mundial est\u00e1 infectada pelo <em>Mycobacterium tuberculosis<\/em> e em risco de desenvolver a doen\u00e7a. H\u00e1 cerca de 8,8 milh\u00f5es de doentes e 1,1 milh\u00f5es de mortes por ano no mundo.<\/p>\n<p style=\"text-align: justify;\">O Brasil ocupa o 17\u00ba lugar entre os 22 pa\u00edses respons\u00e1veis por 82% do total de casos de tuberculose no mundo. Embora seja uma doen\u00e7a pass\u00edvel de ser prevenida, tratada e mesmo curada, ainda mata cerca de 4,7 mil pessoas todos os anos no Brasil. Cada paciente com tuberculose pulmonar que n\u00e3o se trata, pode infectar em m\u00e9dia 10 a 15 pessoas por ano. Alguns fatores contribuem para a dissemina\u00e7\u00e3o da doen\u00e7a, tais como a pobreza e m\u00e1 distribui\u00e7\u00e3o de renda, a AIDS, a desnutri\u00e7\u00e3o, as m\u00e1s condi\u00e7\u00f5es sanit\u00e1rias e a alta densidade populacional.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-882\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2022\/11\/Tuberculose-043.jpg\" alt=\"Tuberculose\" width=\"425\" height=\"254\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>\n<p style=\"text-align: justify;\">Alguns pacientes, entretanto, n\u00e3o exibem nenhum ind\u00edcio da doen\u00e7a, enquanto outros apresentam sintomas aparentemente simples, que n\u00e3o s\u00e3o percebidos durante alguns meses. Pode ser confundida com uma gripe, por exemplo, e evoluir durante 3 a 4 meses sem que a pessoa infectada saiba, ao mesmo tempo em que transmite a doen\u00e7a para outras pessoas. A transmiss\u00e3o da tuberculose \u00e9 direta, de pessoa a pessoa. O doente expele, ao falar, espirrar ou tossir, pequenas got\u00edculas de saliva que podem ser aspiradas por outro indiv\u00edduo.<\/p>\n<p><strong>Preven\u00e7\u00e3o e tratamento:<\/strong><\/p>\n<p style=\"text-align: justify;\">A vacina BCG \u00e9 obrigat\u00f3ria para menores de um ano, pois protege as crian\u00e7as contra as formas mais graves da doen\u00e7a. A melhor forma de prevenir a transmiss\u00e3o da doen\u00e7a \u00e9 fazer o diagn\u00f3stico precoce e iniciar o tratamento adequado o mais r\u00e1pido poss\u00edvel. Com 15 dias ap\u00f3s iniciado o tratamento, a pessoa j\u00e1 n\u00e3o transmite mais a doen\u00e7a. O tratamento deve ser feito por um per\u00edodo m\u00ednimo de 6 meses, diariamente e sem nenhuma interrup\u00e7\u00e3o. O tratamento s\u00f3 termina quando o m\u00e9dico confirmar a cura total do paciente.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\"><strong style=\"font-size: 16px;\">DIA NACIONAL DA HOMEOPATIA<\/strong><\/p>\n<p style=\"text-align: justify;\">O Dia Nacional da Homeopatia foi oficialmente institu\u00eddo em homenagem \u00e0 data de chegada ao Brasil do homeopata franc\u00eas Dr. Benoit Jules Mure (1809-1858), ocorrida em 21 de novembro de 1840.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-883\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2022\/11\/Homeopatia-7ca.jpg\" alt=\"Homeopatia\" width=\"261\" height=\"224\" style=\"display: block; margin-left: auto; margin-right: auto;\" \/><\/p>\n<p style=\"text-align: justify;\">Todos os seres vivos apresentam uma esp\u00e9cie de for\u00e7a organizadora que ajuda a manter os v\u00e1rios tipos de organismo em estado mais ou menos saud\u00e1vel. A perturba\u00e7\u00e3o desta unidade organizada pode ser a primeira etapa de uma enfermidade. Podemos chamar de energia vital, mas podemos tamb\u00e9m cham\u00e1-la de for\u00e7a que mant\u00e9m nossa sa\u00fade em dia.<\/p>\n<p style=\"text-align: justify;\">Considerando-se que cada indiv\u00edduo tem a sua \u201cenergia vital\u201d ou a sua \u201cfor\u00e7a de sa\u00fade\u201d e cada um tem seu \u00f3rg\u00e3o de choque espec\u00edfico, al\u00e9m de uma maneira pr\u00f3pria de adoecer, pode-se afirmar que ele tenha, tamb\u00e9m, seu medicamento homeop\u00e1tico espec\u00edfico. N\u00e3o para a doen\u00e7a, mas para todo seu corpo e todos os seus sintomas. Este medicamento pode devolver sua sa\u00fade, melhorando muito seu mal estar e aqueles sintomas fisiol\u00f3gicos, isto \u00e9, aqueles que mudaram para pior o funcionamento do seu corpo.<\/p>\n<p style=\"text-align: justify;\">Os medicamentos homeop\u00e1ticos s\u00e3o produzidos em farm\u00e1cias de manipula\u00e7\u00e3o e t\u00eam como mat\u00e9ria-prima ervas naturais ou mesmo ra\u00edzes, minerais, animais, entre outras fontes provenientes da natureza.<\/p>\n<p style=\"text-align: justify;\">A ingest\u00e3o de medicamentos homeop\u00e1ticos depende sempre do estado cl\u00ednico do paciente e, por isso, n\u00e3o devem ser tomados ou ter suas doses repetidas sem o conhecimento e a prescri\u00e7\u00e3o do profissional homeopata.<\/p>\n<p style=\"text-align: justify;\">Presente no SUS desde 2006, a homeopatia foi inserida no sistema p\u00fablico de sa\u00fade brasileiro por meio da Pol\u00edtica Nacional de Pr\u00e1ticas Integrativas e Complementares do SUS.<\/p>\n<p style=\"text-align: justify;\">O acesso \u00e9 feito a partir dos servi\u00e7os de sa\u00fade, tanto em unidades b\u00e1sicas como em servi\u00e7os especializados e, at\u00e9 mesmo em hospitais, de acordo a organiza\u00e7\u00e3o dos servi\u00e7os em cada munic\u00edpio.<\/p>\n<p style=\"font-size: 10px; text-align: right;\">Fontes: Minist\u00e9rio da Sa\u00fade e&nbsp;Associa\u00e7\u00e3o Brasileira de Estomaterapia.<\/p>","protected":false},"excerpt":{"rendered":"<p>CALENDARIO M\u00caS DE NOVEMBRO 14\/11 &#8211; Dia Mundial do Diabetes 16\/11 &#8211; Dia Nacional dos Ostomizados 17\/11 &#8211; Dia Mundial da Prematuridade 21\/11 &#8211; Dia Nacional da Homeopatia &nbsp;&nbsp; NOVEMBRO AZUL \u2013 Sa\u00fade do Homem A campanha mundial do Novembro Azul procura conscientizar os homens sobre os cuidados com a sa\u00fade, especialmente na preven\u00e7\u00e3o do [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":876,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[79],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 06:00:51","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/885"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=885"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}