{"id":912,"date":"2015-06-12T21:08:29","date_gmt":"2015-06-13T00:08:29","guid":{"rendered":"http:\/\/webdease2023.intranet.ciasc.gov.br\/2015\/06\/12\/cope-inaugurara-mais-quatro-oficinas-de-trabalho\/"},"modified":"2023-07-13T17:53:23","modified_gmt":"2023-07-13T20:53:23","slug":"cope-inaugurara-mais-quatro-oficinas-de-trabalho","status":"publish","type":"post","link":"https:\/\/sap.sc.gov.br\/en\/cope-inaugurara-mais-quatro-oficinas-de-trabalho\/","title":{"rendered":"Complexo Penitenci\u00e1rio do Estado inaugura mais quatro oficinas"},"content":{"rendered":"<p>Na manh\u00e3 desta segunda-feira (15), no munic\u00edpio de S\u00e3o Pedro de Alcantara, mais um passo rumo a ressocializa\u00e7\u00e3o no sistema prisional catarinense foi dado. Quatro novas oficinas de trabalho foram inauguradas na presen\u00e7a de servidores e autoridades.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-909\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2015\/06\/cope001-d12-1.jpg\" alt=\"cope001\" \/>Quatro empresas catarinenses celebraram um conv\u00eanio com o Estado, atrav\u00e9s da Secretaria de Estado da Justi\u00e7a e Cidadania. Elas oferecer\u00e3o m\u00e3o de obra para aproximadamente 100 reeducandos que, al\u00e9m de receberem treinamento de m\u00e3o de obra qualificada, ser\u00e3o remunerados com um sal\u00e1rio m\u00ednimo nos moldes do Programa Come\u00e7ar de Novo, do Conselho Nacional de Justi\u00e7a.<\/p>\n<p><img decoding=\"async\" class=\"size-full wp-image-910\" src=\"https:\/\/www.sap.sc.gov.br\/wp-content\/uploads\/2015\/06\/cope002-968-1.jpg\" alt=\"cope002\" \/>Estiveram presentes na solenidade representantes das empresas conveniadas Dalannio Bike ME, Precicast Ind\u00fastria e Comercio Ltda, Olsen Ind\u00fastria e Comercio S.A e Stahelin Flores Ltda, Hilberto Ant\u00f4nio Vieira J\u00fanior, Diretor do Complexo, Jo\u00e3o Batista Martins Saturnino, Gerente de Atividades Laborais da Penitenci\u00e1ria, Renato Fernandes Silva, representando do Diretor do Departamento de Administra\u00e7\u00e3o Prisional, Gabriel Airton da Silveira, Diretor da regional da Grande Florian\u00f3polis, Dr. Raul Ara\u00fajo dos Santos Neto, promotor de justi\u00e7a da 10\u00ba Promotoria de S\u00e3o Jos\u00e9, W\u00e2nia Kamienski, representando a Coordenadoria de Execu\u00e7\u00e3o Penal e da Viol\u00eancia Dom\u00e9stica e Familiar contra a Mulher, al\u00e9m de servidores e demais convidados.<\/p>","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 desta segunda-feira (15), no munic\u00edpio de S\u00e3o Pedro de Alcantara, mais um passo rumo a ressocializa\u00e7\u00e3o no sistema prisional catarinense foi dado. Quatro novas oficinas de trabalho foram inauguradas na presen\u00e7a de servidores e autoridades. Quatro empresas catarinenses celebraram um conv\u00eanio com o Estado, atrav\u00e9s da Secretaria de Estado da Justi\u00e7a e Cidadania. [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":14609,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1296],"tags":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 05:59:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/912"}],"collection":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/comments?post=912"}],"version-history":[{"count":0,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/posts\/912\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media\/14609"}],"wp:attachment":[{"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/media?parent=912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/categories?post=912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sap.sc.gov.br\/en\/wp-json\/wp\/v2\/tags?post=912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}